{"id":2403,"date":"2020-06-08T07:19:47","date_gmt":"2020-06-08T07:19:47","guid":{"rendered":"https:\/\/www.uffizio.com\/?p=2403"},"modified":"2026-05-22T06:28:12","modified_gmt":"2026-05-22T06:28:12","slug":"how-telematics-industry-has-changed-during-the-pandemic","status":"publish","type":"post","link":"https:\/\/uffizio.com\/th\/blog\/how-telematics-industry-has-changed-during-the-pandemic\/","title":{"rendered":"\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e40\u0e17\u0e40\u0e25\u0e40\u0e21\u0e15\u0e34\u0e01\u0e2a\u0e4c\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e41\u0e1b\u0e25\u0e07\u0e44\u0e1b\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23\u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07\u0e01\u0e32\u0e23\u0e23\u0e30\u0e1a\u0e32\u0e14\u0e43\u0e2b\u0e0d\u0e48"},"content":{"rendered":"<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" class=\"wp-image-9908\" src=\"https:\/\/www.uffizio.com\/wp-content\/uploads\/2020\/06\/telematics-fleet-1-1024x683-1.jpg\" alt=\"telematics-fleet\" srcset=\"https:\/\/uffizio.com\/wp-content\/uploads\/2020\/06\/telematics-fleet-1-1024x683-1.jpg 1024w, https:\/\/uffizio.com\/wp-content\/uploads\/2020\/06\/telematics-fleet-1-1024x683-1-300x200.jpg 300w, https:\/\/uffizio.com\/wp-content\/uploads\/2020\/06\/telematics-fleet-1-1024x683-1-768x512.jpg 768w, https:\/\/uffizio.com\/wp-content\/uploads\/2020\/06\/telematics-fleet-1-1024x683-1-810x540.jpg 810w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e15\u0e49\u0e2d\u0e07\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e15\u0e48\u0e2d\u0e44\u0e1b\u0e41\u0e21\u0e49\u0e27\u0e48\u0e32\u0e42\u0e25\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e40\u0e1c\u0e0a\u0e34\u0e0d\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e23\u0e30\u0e1a\u0e32\u0e14\u0e43\u0e2b\u0e0d\u0e48\u0e02\u0e2d\u0e07\u0e44\u0e27\u0e23\u0e31\u0e2a\u0e42\u0e04\u0e42\u0e23\u0e19\u0e32 \u0e42\u0e14\u0e22\u0e44\u0e21\u0e48\u0e21\u0e35\u0e02\u0e49\u0e2d\u0e41\u0e21\u0e49\u0e43\u0e14\u0e46 \u0e20\u0e32\u0e04\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e17\u0e31\u0e48\u0e27\u0e42\u0e25\u0e01\u0e44\u0e14\u0e49\u0e1b\u0e23\u0e31\u0e1a\u0e43\u0e0a\u0e49\u0e01\u0e25\u0e22\u0e38\u0e17\u0e18\u0e4c\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e08\u0e32\u0e01\u0e23\u0e30\u0e22\u0e30\u0e44\u0e01\u0e25\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e15\u0e34\u0e1a\u0e42\u0e15\u0e44\u0e14\u0e49\u0e41\u0e21\u0e49\u0e43\u0e19\u0e20\u0e32\u0e27\u0e30\u0e27\u0e34\u0e01\u0e24\u0e15<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">\u0e15\u0e25\u0e32\u0e14\u0e40\u0e17\u0e40\u0e25\u0e40\u0e21\u0e15\u0e34\u0e01\u0e2a\u0e4c\u0e17\u0e31\u0e48\u0e27\u0e42\u0e25\u0e01\u0e01\u0e47\u0e44\u0e21\u0e48\u0e1e\u0e49\u0e19\u0e08\u0e32\u0e01\u0e1c\u0e25\u0e01\u0e23\u0e30\u0e17\u0e1a\u0e02\u0e2d\u0e07\u0e42\u0e04\u0e27\u0e34\u0e14-19 \u0e40\u0e0a\u0e48\u0e19\u0e01\u0e31\u0e19 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e01\u0e32\u0e23\u0e25\u0e14\u0e25\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e09\u0e31\u0e1a\u0e1e\u0e25\u0e31\u0e19\u0e02\u0e2d\u0e07\u0e22\u0e2d\u0e14\u0e02\u0e32\u0e22\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e2d\u0e31\u0e19\u0e14\u0e35\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e08\u0e23\u0e08\u0e32\u0e15\u0e48\u0e2d\u0e23\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e1c\u0e25\u0e34\u0e15\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23 \u0e41\u0e23\u0e07\u0e01\u0e14\u0e14\u0e31\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e34\u0e14\u0e08\u0e32\u0e01\u0e42\u0e23\u0e04\u0e23\u0e30\u0e1a\u0e32\u0e14\u0e43\u0e19\u0e01\u0e32\u0e23\u0e40\u0e23\u0e48\u0e07\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e41\u0e1b\u0e25\u0e07\u0e17\u0e32\u0e07\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e44\u0e1b\u0e44\u0e14\u0e49\u0e17\u0e35\u0e48\u0e08\u0e30\u0e21\u0e35\u0e1a\u0e17\u0e1a\u0e32\u0e17\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e43\u0e2b\u0e21\u0e48\u0e43\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e19\u0e35\u0e49\u00a0<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">\u0e2a\u0e16\u0e34\u0e15\u0e34\u0e14\u0e49\u0e32\u0e19\u0e40\u0e17\u0e40\u0e25\u0e40\u0e21\u0e15\u0e34\u0e01\u0e2a\u0e4c\u0e04\u0e32\u0e14\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e2d\u0e31\u0e15\u0e23\u0e32\u0e01\u0e32\u0e23\u0e40\u0e15\u0e34\u0e1a\u0e42\u0e15\u0e40\u0e09\u0e25\u0e35\u0e48\u0e22\u0e15\u0e48\u0e2d\u0e1b\u0e35\u0e41\u0e1a\u0e1a\u0e17\u0e1a\u0e15\u0e49\u0e19\u0e17\u0e35\u0e48 20.7% \u0e15\u0e32\u0e21\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e08\u0e32\u0e01 Mordor Intelligence \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23\u0e01\u0e47\u0e15\u0e32\u0e21 \u0e01\u0e32\u0e23\u0e23\u0e30\u0e1a\u0e32\u0e14\u0e02\u0e2d\u0e07 COVID-19 \u0e21\u0e35\u0e41\u0e19\u0e27\u0e42\u0e19\u0e49\u0e21\u0e17\u0e35\u0e48\u0e08\u0e30\u0e2a\u0e48\u0e07\u0e1c\u0e25\u0e01\u0e23\u0e30\u0e17\u0e1a\u0e40\u0e0a\u0e34\u0e07\u0e25\u0e1a\u0e15\u0e48\u0e2d\u0e15\u0e25\u0e32\u0e14\u0e17\u0e35\u0e48\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e43\u0e19\u0e23\u0e30\u0e22\u0e30\u0e2a\u0e31\u0e49\u0e19\u00a0<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">\u0e20\u0e32\u0e1e\u0e23\u0e27\u0e21\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e40\u0e17\u0e40\u0e25\u0e40\u0e21\u0e15\u0e34\u0e01\u0e2a\u0e4c\u0e41\u0e2a\u0e14\u0e07\u0e43\u0e2b\u0e49\u0e40\u0e2b\u0e47\u0e19\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e41\u0e1b\u0e25\u0e07\u0e17\u0e35\u0e48\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e02\u0e36\u0e49\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e23\u0e27\u0e14\u0e40\u0e23\u0e47\u0e27\u0e43\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19 \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e32\u0e01\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e43\u0e2b\u0e49\u0e2d\u0e22\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19\u0e41\u0e25\u0e30\u0e23\u0e31\u0e01\u0e29\u0e32\u0e23\u0e30\u0e22\u0e30\u0e2b\u0e48\u0e32\u0e07\u0e17\u0e32\u0e07\u0e2a\u0e31\u0e07\u0e04\u0e21 \u0e01\u0e32\u0e23\u0e23\u0e30\u0e1a\u0e32\u0e14\u0e43\u0e2b\u0e0d\u0e48\u0e08\u0e36\u0e07\u0e01\u0e23\u0e30\u0e15\u0e38\u0e49\u0e19\u0e43\u0e2b\u0e49\u0e1e\u0e27\u0e01\u0e40\u0e02\u0e32\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e19\u0e19\u0e41\u0e25\u0e30\u0e08\u0e2d\u0e14\u0e23\u0e16\u0e17\u0e34\u0e49\u0e07\u0e44\u0e27\u0e49\u0e42\u0e14\u0e22\u0e44\u0e21\u0e48\u0e14\u0e31\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e19\u0e15\u0e4c\u0e43\u0e19\u0e1a\u0e23\u0e34\u0e40\u0e27\u0e13\u0e1a\u0e49\u0e32\u0e19\u0e41\u0e25\u0e30\u0e42\u0e23\u0e07\u0e23\u0e16\u00a0<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e32\u0e01\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e02\u0e2d\u0e07\u0e15\u0e25\u0e32\u0e14\u0e40\u0e17\u0e40\u0e25\u0e40\u0e21\u0e15\u0e34\u0e01\u0e2a\u0e4c\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e42\u0e25\u0e01 \u0e01\u0e32\u0e23\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e41\u0e1b\u0e25\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e20\u0e32\u0e04\u0e2a\u0e48\u0e27\u0e19\u0e19\u0e35\u0e49\u0e08\u0e36\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e34\u0e48\u0e07\u0e17\u0e35\u0e48\u0e2b\u0e25\u0e35\u0e01\u0e40\u0e25\u0e35\u0e48\u0e22\u0e07\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49 \u0e41\u0e25\u0e30\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e20\u0e31\u0e22\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e01\u0e47\u0e40\u0e0a\u0e48\u0e19\u0e01\u0e31\u0e19 <strong><a href=\"https:\/\/www.uffizio-telematics.com\/\/fleet-management-software\/\" target=\"_blank\" rel=\"noreferrer noopener\">\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30<\/a><\/strong>\u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e41\u0e25\u0e30\u0e1e\u0e24\u0e15\u0e34\u0e01\u0e23\u0e23\u0e21\u0e02\u0e2d\u0e07\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e08\u0e30\u0e15\u0e49\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e15\u0e31\u0e27\u0e43\u0e2b\u0e49\u0e40\u0e02\u0e49\u0e32\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e41\u0e1b\u0e25\u0e07\u0e40\u0e2b\u0e25\u0e48\u0e32\u0e19\u0e35\u0e49\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e15\u0e34\u0e1a\u0e42\u0e15\u0e44\u0e14\u0e49\u0e43\u0e19\u0e2a\u0e20\u0e32\u0e27\u0e30\u0e1b\u0e01\u0e15\u0e34\u0e43\u0e2b\u0e21\u0e48\u0e02\u0e2d\u0e07\u0e20\u0e32\u0e04\u0e2a\u0e48\u0e27\u0e19\u0e40\u0e17\u0e40\u0e25\u0e40\u0e21\u0e15\u0e34\u0e01\u0e2a\u0e4c\u00a0<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">\u0e15\u0e48\u0e2d\u0e44\u0e1b\u0e19\u0e35\u0e49\u0e04\u0e37\u0e2d\u0e41\u0e19\u0e27\u0e42\u0e19\u0e49\u0e21\u0e17\u0e35\u0e48\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e1a\u0e32\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e40\u0e17\u0e40\u0e25\u0e40\u0e21\u0e15\u0e34\u0e01\u0e2a\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e34\u0e14\u0e02\u0e36\u0e49\u0e19\u0e08\u0e32\u0e01\u0e27\u0e34\u0e01\u0e24\u0e15 COVID-19:\u00a0<\/p>\r\n\r\n\r\n\r\n<h3 class=\"wp-block-heading\" id=\"h-setting-up-new-safety-guidelines\">\u0e01\u0e32\u0e23\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e43\u0e2b\u0e21\u0e48<\/h3>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2a\u0e35\u0e48\u0e22\u0e07\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e39\u0e48\u0e44\u0e01\u0e25\u0e08\u0e32\u0e01\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07 \u0e41\u0e25\u0e30\u0e43\u0e19\u0e02\u0e13\u0e30\u0e17\u0e35\u0e48\u0e22\u0e31\u0e07\u0e44\u0e21\u0e48\u0e21\u0e35\u0e27\u0e34\u0e18\u0e35\u0e43\u0e14\u0e17\u0e35\u0e48\u0e08\u0e30\u0e40\u0e2d\u0e32\u0e0a\u0e19\u0e30\u0e01\u0e32\u0e23\u0e23\u0e30\u0e1a\u0e32\u0e14\u0e43\u0e2b\u0e0d\u0e48\u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e41\u0e19\u0e48\u0e19\u0e2d\u0e19 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e40\u0e17\u0e40\u0e25\u0e40\u0e21\u0e15\u0e34\u0e01\u0e2a\u0e4c\u0e44\u0e14\u0e49\u0e19\u0e33\u0e21\u0e32\u0e15\u0e23\u0e01\u0e32\u0e23\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e21\u0e32\u0e43\u0e0a\u0e49\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e23\u0e48\u0e01\u0e23\u0e30\u0e08\u0e32\u0e22\u0e02\u0e2d\u0e07\u0e44\u0e27\u0e23\u0e31\u0e2a\u0e41\u0e25\u0e30\u0e1b\u0e01\u0e1b\u0e49\u0e2d\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e15\u0e19\u00a0<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14 \u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e41\u0e25\u0e30\u0e2a\u0e38\u0e02\u0e2d\u0e19\u0e32\u0e21\u0e31\u0e22 \u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e31\u0e08\u0e08\u0e31\u0e22\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e17\u0e35\u0e48\u0e1c\u0e25\u0e31\u0e01\u0e14\u0e31\u0e19\u0e41\u0e19\u0e27\u0e42\u0e19\u0e49\u0e21\u0e43\u0e2b\u0e21\u0e48\u0e46 \u0e43\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e40\u0e17\u0e40\u0e25\u0e40\u0e21\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e43\u0e19\u0e20\u0e32\u0e04\u0e2a\u0e48\u0e27\u0e19\u0e19\u0e35\u0e49\u0e44\u0e14\u0e49\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e43\u0e2b\u0e49\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e25\u0e49\u0e32\u0e07\u0e21\u0e37\u0e2d\u0e1a\u0e48\u0e2d\u0e22\u0e46 \u0e42\u0e14\u0e22\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e40\u0e25\u0e47\u0e01\u0e46 \u0e44\u0e27\u0e49\u0e43\u0e19\u0e2b\u0e49\u0e2d\u0e07\u0e17\u0e33\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30 \u0e1a\u0e32\u0e07\u0e2a\u0e16\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e22\u0e31\u0e07\u0e44\u0e14\u0e49\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e40\u0e08\u0e25\u0e25\u0e49\u0e32\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e40\u0e0a\u0e48\u0e19 \u0e2b\u0e19\u0e49\u0e32\u0e01\u0e32\u0e01\u0e2d\u0e19\u0e32\u0e21\u0e31\u0e22\u0e41\u0e25\u0e30\u0e16\u0e38\u0e07\u0e21\u0e37\u0e2d \u0e04\u0e27\u0e1a\u0e04\u0e39\u0e48\u0e44\u0e1b\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e17\u0e35\u0e48\u0e08\u0e33\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e0a\u0e30\u0e25\u0e2d\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e23\u0e48\u0e01\u0e23\u0e30\u0e08\u0e32\u0e22\u0e02\u0e2d\u0e07\u0e44\u0e27\u0e23\u0e31\u0e2a\u0e14\u0e49\u0e27\u0e22\u00a0<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">\u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49 \u0e02\u0e2d\u0e43\u0e2b\u0e49\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e43\u0e19\u0e17\u0e35\u0e21\u0e43\u0e0a\u0e49\u0e1c\u0e49\u0e32\u0e40\u0e0a\u0e47\u0e14\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e1a\u0e48\u0e2d\u0e22\u0e46 \u0e17\u0e38\u0e01\u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48\u0e44\u0e2d\u0e2b\u0e23\u0e37\u0e2d\u0e08\u0e32\u0e21 \u0e41\u0e25\u0e30\u0e17\u0e34\u0e49\u0e07\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e40\u0e2b\u0e25\u0e48\u0e32\u0e19\u0e35\u0e49\u0e25\u0e07\u0e43\u0e19\u0e16\u0e31\u0e07\u0e02\u0e22\u0e30\u0e23\u0e27\u0e21\u0e01\u0e31\u0e1a\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e41\u0e25\u0e49\u0e27\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21 \u0e41\u0e25\u0e30\u0e02\u0e2d\u0e43\u0e2b\u0e49\u0e2b\u0e25\u0e35\u0e01\u0e40\u0e25\u0e35\u0e48\u0e22\u0e07\u0e01\u0e32\u0e23\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e01\u0e25\u0e49\u0e0a\u0e34\u0e14\u0e01\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22\u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e41\u0e2d crowded \u0e0b\u0e36\u0e48\u0e07\u0e21\u0e35\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e15\u0e34\u0e14\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e2a\u0e39\u0e07\u0e01\u0e27\u0e48\u0e32\u00a0<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e32\u0e01\u0e07\u0e32\u0e19\u0e27\u0e34\u0e08\u0e31\u0e22\u0e23\u0e30\u0e1a\u0e38\u0e27\u0e48\u0e32\u0e44\u0e27\u0e23\u0e31\u0e2a\u0e42\u0e04\u0e42\u0e23\u0e19\u0e32\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2d\u0e22\u0e39\u0e48\u0e23\u0e2d\u0e14\u0e1a\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e1c\u0e34\u0e27\u0e44\u0e14\u0e49\u0e19\u0e32\u0e19\u0e16\u0e36\u0e07 9 \u0e27\u0e31\u0e19 \u0e01\u0e32\u0e23\u0e06\u0e48\u0e32\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e1a\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e1c\u0e34\u0e27\u0e17\u0e35\u0e48\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13\u0e2a\u0e31\u0e21\u0e1c\u0e31\u0e2a\u0e2d\u0e22\u0e39\u0e48\u0e15\u0e25\u0e2d\u0e14\u0e40\u0e27\u0e25\u0e32\u0e08\u0e36\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e34\u0e48\u0e07\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e43\u0e19\u0e01\u0e32\u0e23\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e23\u0e48\u0e23\u0e30\u0e1a\u0e32\u0e14\u0e02\u0e2d\u0e07\u0e44\u0e27\u0e23\u0e31\u0e2a\u0e42\u0e04\u0e42\u0e23\u0e19\u0e32 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e2b\u0e0d\u0e48\u0e44\u0e14\u0e49\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e19\u0e49\u0e33\u0e22\u0e32\u0e06\u0e48\u0e32\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e41\u0e25\u0e30\u0e1c\u0e49\u0e32\u0e40\u0e0a\u0e47\u0e14\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e02\u0e31\u0e1a\u0e23\u0e16 \u0e41\u0e25\u0e30\u0e02\u0e2d\u0e43\u0e2b\u0e49\u0e1e\u0e27\u0e01\u0e40\u0e02\u0e32\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e1e\u0e27\u0e07\u0e21\u0e32\u0e25\u0e31\u0e22 \u0e21\u0e37\u0e2d\u0e08\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e15\u0e39 \u0e41\u0e1c\u0e07\u0e2b\u0e19\u0e49\u0e32\u0e1b\u0e31\u0e14 \u0e04\u0e31\u0e19\u0e40\u0e01\u0e35\u0e22\u0e23\u0e4c \u0e17\u0e35\u0e48\u0e27\u0e32\u0e07\u0e41\u0e02\u0e19 \u0e41\u0e25\u0e30\u0e40\u0e1a\u0e32\u0e30\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u00a0<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">\u0e41\u0e19\u0e48\u0e19\u0e2d\u0e19\u0e27\u0e48\u0e32 \u0e41\u0e19\u0e27\u0e42\u0e19\u0e49\u0e21\u0e43\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e40\u0e17\u0e40\u0e25\u0e40\u0e21\u0e15\u0e34\u0e01\u0e2a\u0e4c\u0e08\u0e30\u0e44\u0e21\u0e48\u0e2a\u0e21\u0e1a\u0e39\u0e23\u0e13\u0e4c\u0e2b\u0e32\u0e01\u0e1b\u0e23\u0e32\u0e28\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32\u0e23\u0e30\u0e22\u0e30\u0e2b\u0e48\u0e32\u0e07\u0e17\u0e32\u0e07\u0e2a\u0e31\u0e07\u0e04\u0e21 \u0e2a\u0e16\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e44\u0e14\u0e49\u0e2a\u0e31\u0e48\u0e07\u0e43\u0e2b\u0e49\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e02\u0e31\u0e1a\u0e23\u0e16\u0e2b\u0e25\u0e35\u0e01\u0e40\u0e25\u0e35\u0e48\u0e22\u0e07\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e17\u0e32\u0e07\u0e01\u0e32\u0e22\u0e20\u0e32\u0e1e\u0e01\u0e31\u0e1a\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e17\u0e38\u0e01\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49 \u0e22\u0e31\u0e07\u0e21\u0e35\u0e01\u0e32\u0e23\u0e1a\u0e31\u0e07\u0e04\u0e31\u0e1a\u0e43\u0e0a\u0e49\u0e01\u0e0e\u0e23\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e1a\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e08\u0e33\u0e19\u0e27\u0e19\u0e04\u0e19\u0e43\u0e19\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30 \u0e0b\u0e36\u0e48\u0e07\u0e08\u0e33\u0e01\u0e31\u0e14\u0e44\u0e27\u0e49\u0e17\u0e35\u0e48 1-2 \u0e04\u0e19\u00a0<\/p>\r\n\r\n\r\n\r\n<h3 class=\"wp-block-heading\" id=\"h-shift-to-home-based-work\">\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e44\u0e1b\u0e17\u0e33\u0e07\u0e32\u0e19\u0e08\u0e32\u0e01\u0e17\u0e35\u0e48\u0e1a\u0e49\u0e32\u0e19\u00a0<\/h3>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e08\u0e33\u0e19\u0e27\u0e19\u0e21\u0e32\u0e01\u0e17\u0e31\u0e48\u0e27\u0e42\u0e25\u0e01\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e40\u0e04\u0e22\u0e21\u0e35\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e17\u0e33\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e1a\u0e49\u0e32\u0e19\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e19 \u0e16\u0e39\u0e01\u0e1a\u0e31\u0e07\u0e04\u0e31\u0e1a\u0e43\u0e2b\u0e49\u0e15\u0e49\u0e2d\u0e07\u0e17\u0e33\u0e40\u0e0a\u0e48\u0e19\u0e19\u0e31\u0e49\u0e19\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e32\u0e01\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e01\u0e15\u0e31\u0e27\u0e2d\u0e22\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e0a\u0e48\u0e27\u0e22\u0e0a\u0e30\u0e25\u0e2d\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e23\u0e48\u0e23\u0e30\u0e1a\u0e32\u0e14\u0e02\u0e2d\u0e07\u0e44\u0e27\u0e23\u0e31\u0e2a \u0e41\u0e21\u0e49\u0e27\u0e48\u0e32\u0e2a\u0e34\u0e48\u0e07\u0e19\u0e35\u0e49\u0e08\u0e30\u0e2a\u0e48\u0e07\u0e1c\u0e25\u0e01\u0e23\u0e30\u0e17\u0e1a\u0e15\u0e48\u0e2d\u0e2b\u0e25\u0e32\u0e22\u0e20\u0e32\u0e04\u0e2a\u0e48\u0e27\u0e19 \u0e41\u0e15\u0e48\u0e20\u0e32\u0e1e\u0e23\u0e27\u0e21\u0e02\u0e2d\u0e07\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e42\u0e17\u0e23\u0e04\u0e21\u0e19\u0e32\u0e04\u0e21\u0e41\u0e2a\u0e14\u0e07\u0e43\u0e2b\u0e49\u0e40\u0e2b\u0e47\u0e19\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e41\u0e1b\u0e25\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e23\u0e27\u0e14\u0e40\u0e23\u0e47\u0e27\u0e43\u0e19\u0e41\u0e07\u0e48\u0e02\u0e2d\u0e07\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e08\u0e33\u0e19\u0e27\u0e19\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e02\u0e36\u0e49\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e22\u0e46 \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e1a\u0e1a\u0e1a\u0e32\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e16\u0e32\u0e27\u0e23\u00a0<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23 \u0e40\u0e0a\u0e48\u0e19 \u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e01\u0e32\u0e23\u0e40\u0e14\u0e34\u0e19\u0e23\u0e16 \u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e15\u0e32\u0e21\u0e01\u0e0e\u0e23\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e1a\u0e14\u0e49\u0e32\u0e19\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e44\u0e14\u0e49\u0e16\u0e39\u0e01\u0e42\u0e2d\u0e19\u0e22\u0e49\u0e32\u0e22\u0e44\u0e1b\u0e17\u0e35\u0e48... <a href=\"https:\/\/rocketdigit.com\/remote-working\/\" target=\"_blank\" rel=\"noopener\">\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e23\u0e30\u0e22\u0e30\u0e44\u0e01\u0e25<\/a> \u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e43\u0e19\u0e10\u0e32\u0e19\u0e30\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e17\u0e35\u0e48\u0e02\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e0a\u0e48\u0e27\u0e22\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e08\u0e32\u0e01 <a href=\"https:\/\/uffizio.com\/th\/\" target=\"_blank\" rel=\"noreferrer noopener\">\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07 GPS<\/a> \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e0a\u0e48\u0e27\u0e22\u0e43\u0e2b\u0e49\u0e17\u0e35\u0e21\u0e07\u0e32\u0e19\u0e17\u0e33\u0e07\u0e32\u0e19\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e23\u0e32\u0e1a\u0e23\u0e37\u0e48\u0e19\u0e41\u0e25\u0e30\u0e25\u0e14\u0e2d\u0e38\u0e1b\u0e2a\u0e23\u0e23\u0e04\u0e15\u0e48\u0e32\u0e07\u0e46\u00a0<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e2b\u0e0d\u0e48\u0e43\u0e19\u0e20\u0e32\u0e04\u0e2a\u0e48\u0e27\u0e19\u0e19\u0e35\u0e49\u0e44\u0e14\u0e49\u0e19\u0e33\u0e40\u0e17\u0e23\u0e19\u0e14\u0e4c\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e40\u0e17\u0e40\u0e25\u0e40\u0e21\u0e15\u0e34\u0e01\u0e2a\u0e4c\u0e21\u0e32\u0e43\u0e0a\u0e49\u0e41\u0e25\u0e49\u0e27 \u0e40\u0e0a\u0e48\u0e19 \u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c\u0e17\u0e35\u0e48\u0e21\u0e35\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e0a\u0e48\u0e27\u0e22\u0e43\u0e19\u0e01\u0e32\u0e23\u0e19\u0e33\u0e01\u0e25\u0e22\u0e38\u0e17\u0e18\u0e4c\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e23\u0e30\u0e22\u0e30\u0e44\u0e01\u0e25\u0e21\u0e32\u0e43\u0e0a\u0e49\u0e44\u0e14\u0e49 \u0e14\u0e31\u0e07\u0e40\u0e0a\u0e48\u0e19\u0e17\u0e35\u0e48\u0e23\u0e30\u0e1a\u0e38\u0e44\u0e27\u0e49\u0e43\u0e19\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e19\u0e35\u0e49\u00a0<a href=\"https:\/\/financesonline.com\/best-technology-for-working-remotely-tips-essential-solutions\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">\u0e1a\u0e17\u0e04\u0e27\u0e32\u0e21\u0e43\u0e2b\u0e21\u0e48\u0e08\u0e32\u0e01 FinancesOnline \u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e0a\u0e31\u0e49\u0e19\u0e19\u0e33\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e08\u0e32\u0e01\u0e23\u0e30\u0e22\u0e30\u0e44\u0e01\u0e25<\/a>\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e40\u0e2b\u0e25\u0e48\u0e32\u0e19\u0e35\u0e49\u0e16\u0e39\u0e01\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e21\u0e32\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e0a\u0e48\u0e27\u0e22\u0e43\u0e2b\u0e49\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e27\u0e31\u0e19\u0e43\u0e19\u0e15\u0e25\u0e32\u0e14\u0e40\u0e17\u0e40\u0e25\u0e40\u0e21\u0e15\u0e34\u0e01\u0e2a\u0e4c\u0e44\u0e14\u0e49 \u0e40\u0e0a\u0e48\u0e19 \u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e01\u0e32\u0e23\u0e41\u0e08\u0e49\u0e07\u0e40\u0e27\u0e25\u0e32\u0e16\u0e36\u0e07\u0e17\u0e35\u0e48\u0e2b\u0e21\u0e32\u0e22\u0e42\u0e14\u0e22\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13\u0e43\u0e2b\u0e49\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e17\u0e23\u0e32\u0e1a \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e40\u0e2b\u0e15\u0e38\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e14\u0e49\u0e32\u0e19\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22<\/p>\r\n\r\n\r\n\r\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" class=\"alignnone wp-image-65062 size-full\" src=\"https:\/\/uffizio.com\/wp-content\/uploads\/2020\/06\/hand-sanitizer-face-masks-and-letter-tiles-spelling-safe-hands-1024x683-1.jpg\" alt=\"\" width=\"1024\" height=\"683\" srcset=\"https:\/\/uffizio.com\/wp-content\/uploads\/2020\/06\/hand-sanitizer-face-masks-and-letter-tiles-spelling-safe-hands-1024x683-1.jpg 1024w, https:\/\/uffizio.com\/wp-content\/uploads\/2020\/06\/hand-sanitizer-face-masks-and-letter-tiles-spelling-safe-hands-1024x683-1-300x200.jpg 300w, https:\/\/uffizio.com\/wp-content\/uploads\/2020\/06\/hand-sanitizer-face-masks-and-letter-tiles-spelling-safe-hands-1024x683-1-768x512.jpg 768w, https:\/\/uffizio.com\/wp-content\/uploads\/2020\/06\/hand-sanitizer-face-masks-and-letter-tiles-spelling-safe-hands-1024x683-1-18x12.jpg 18w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\r\n\r\n\r\n\r\n<h3 class=\"wp-block-heading\" id=\"h-tracking-employees\">\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u00a0<\/h3>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">\u0e21\u0e32\u0e15\u0e23\u0e01\u0e32\u0e23\u0e40\u0e27\u0e49\u0e19\u0e23\u0e30\u0e22\u0e30\u0e2b\u0e48\u0e32\u0e07\u0e17\u0e32\u0e07\u0e2a\u0e31\u0e07\u0e04\u0e21\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e21\u0e32\u0e01\u0e19\u0e31\u0e1a\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e01\u0e32\u0e23\u0e23\u0e30\u0e1a\u0e32\u0e14\u0e02\u0e2d\u0e07\u0e44\u0e27\u0e23\u0e31\u0e2a\u0e42\u0e04\u0e42\u0e23\u0e19\u0e32 \u0e41\u0e25\u0e30\u0e02\u0e13\u0e30\u0e17\u0e35\u0e48\u0e42\u0e25\u0e01\u0e04\u0e48\u0e2d\u0e22\u0e46 \u0e1f\u0e37\u0e49\u0e19\u0e15\u0e31\u0e27\u0e08\u0e32\u0e01\u0e20\u0e32\u0e27\u0e30\u0e2b\u0e22\u0e38\u0e14\u0e0a\u0e30\u0e07\u0e31\u0e01\u0e0a\u0e31\u0e48\u0e27\u0e04\u0e23\u0e32\u0e27 \u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e01\u0e47\u0e16\u0e39\u0e01\u0e40\u0e23\u0e35\u0e22\u0e01\u0e23\u0e49\u0e2d\u0e07\u0e43\u0e2b\u0e49\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e15\u0e32\u0e21\u0e21\u0e32\u0e15\u0e23\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e21\u0e31\u0e48\u0e19\u0e43\u0e08\u0e27\u0e48\u0e32\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e02\u0e2d\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e2a\u0e20\u0e32\u0e1e\u0e17\u0e35\u0e48\u0e14\u0e35\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21\u00a0<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">\u0e41\u0e21\u0e49\u0e27\u0e48\u0e32\u0e1c\u0e39\u0e49\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e08\u0e30\u0e44\u0e21\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2d\u0e22\u0e39\u0e48\u0e14\u0e39\u0e41\u0e25\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e43\u0e19\u0e17\u0e35\u0e21\u0e44\u0e14\u0e49\u0e17\u0e38\u0e01\u0e17\u0e35\u0e48\u0e17\u0e38\u0e01\u0e40\u0e27\u0e25\u0e32\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e21\u0e32\u0e15\u0e23\u0e01\u0e32\u0e23\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19 \u0e41\u0e15\u0e48\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e17\u0e40\u0e25\u0e40\u0e21\u0e15\u0e34\u0e01\u0e2a\u0e4c\u0e01\u0e47\u0e40\u0e1b\u0e34\u0e14\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e43\u0e2b\u0e49\u0e17\u0e33\u0e40\u0e0a\u0e48\u0e19\u0e19\u0e31\u0e49\u0e19\u0e44\u0e14\u0e49\u0e42\u0e14\u0e22\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e23\u0e30\u0e1a\u0e1a\u00a0<a href=\"https:\/\/uffizio.com\/th\/blog\/personal-tracker-and-proximity-solution-for-safer-work-environment-during-covid-19\/\" target=\"_blank\" rel=\"noreferrer noopener\">\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e2a\u0e48\u0e27\u0e19\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e41\u0e25\u0e30\u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e19\u0e15\u0e23\u0e27\u0e08\u0e08\u0e31\u0e1a\u0e23\u0e30\u0e22\u0e30\u0e43\u0e01\u0e25\u0e49\u00a0<\/a>\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e19\u0e35\u0e49\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e41\u0e25\u0e30\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e02\u0e2d\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e44\u0e14\u0e49 \u0e04\u0e38\u0e13\u0e2a\u0e21\u0e1a\u0e31\u0e15\u0e34\u0e1a\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e02\u0e2d\u0e07\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e43\u0e2b\u0e21\u0e48\u0e19\u0e35\u0e49 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e01\u0e32\u0e23\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e15\u0e48\u0e2d\u0e01\u0e31\u0e1a\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e2a\u0e48\u0e27\u0e19\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e27\u0e48\u0e32\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e23\u0e31\u0e01\u0e29\u0e32\u0e23\u0e30\u0e22\u0e30\u0e2b\u0e48\u0e32\u0e07\u0e17\u0e35\u0e48\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e08\u0e32\u0e01\u0e01\u0e31\u0e19\u0e41\u0e25\u0e30\u0e01\u0e31\u0e19 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49\u0e22\u0e31\u0e07\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e41\u0e2a\u0e14\u0e07\u0e23\u0e32\u0e22\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e48\u0e2d\u0e23\u0e32\u0e22\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2a\u0e35\u0e48\u0e22\u0e07 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e25\u0e07\u0e40\u0e27\u0e25\u0e32\u0e40\u0e02\u0e49\u0e32\u0e07\u0e32\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e44\u0e14\u0e49\u0e2d\u0e35\u0e01\u0e14\u0e49\u0e27\u0e22\u00a0<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">\u0e2b\u0e32\u0e01\u0e40\u0e01\u0e34\u0e14\u0e2a\u0e16\u0e32\u0e19\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e40\u0e25\u0e27\u0e23\u0e49\u0e32\u0e22\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e41\u0e25\u0e30\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13\u0e15\u0e34\u0e14\u0e40\u0e0a\u0e37\u0e49\u0e2d \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e27\u0e48\u0e32\u0e43\u0e04\u0e23\u0e1a\u0e49\u0e32\u0e07\u0e17\u0e35\u0e48\u0e2a\u0e31\u0e21\u0e1c\u0e31\u0e2a\u0e01\u0e31\u0e1a\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e15\u0e34\u0e14\u0e40\u0e0a\u0e37\u0e49\u0e2d \u0e1a\u0e38\u0e04\u0e04\u0e25\u0e40\u0e2b\u0e25\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19\u0e08\u0e30\u0e16\u0e39\u0e01\u0e04\u0e31\u0e14\u0e2d\u0e2d\u0e01\u0e41\u0e25\u0e30\u0e19\u0e33\u0e44\u0e1b\u0e01\u0e31\u0e01\u0e15\u0e31\u0e27 \u0e2b\u0e23\u0e37\u0e2d\u0e41\u0e19\u0e30\u0e19\u0e33\u0e43\u0e2b\u0e49\u0e1e\u0e31\u0e01\u0e2d\u0e22\u0e39\u0e48\u0e17\u0e35\u0e48\u0e1a\u0e49\u0e32\u0e19\u0e41\u0e25\u0e30\u0e2b\u0e22\u0e38\u0e14\u0e17\u0e33\u0e07\u0e32\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e34\u0e14\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u00a0<\/p>\r\n\r\n\r\n\r\n<h3 class=\"wp-block-heading\" id=\"h-enhancing-overall-mobility-cost\">\u0e01\u0e32\u0e23\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19\u0e17\u0e38\u0e19\u0e01\u0e32\u0e23\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e22\u0e49\u0e32\u0e22\u0e42\u0e14\u0e22\u0e23\u0e27\u0e21<\/h3>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e17\u0e35\u0e48\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e40\u0e23\u0e34\u0e48\u0e21\u0e1e\u0e34\u0e08\u0e32\u0e23\u0e13\u0e32\u0e17\u0e35\u0e48\u0e08\u0e30\u0e19\u0e33\u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e21\u0e32\u0e43\u0e0a\u0e49\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e25\u0e14\u0e15\u0e49\u0e19\u0e17\u0e38\u0e19\u0e01\u0e32\u0e23\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e42\u0e14\u0e22\u0e23\u0e27\u0e21\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e44\u0e27\u0e23\u0e31\u0e2a\u0e2b\u0e21\u0e14\u0e44\u0e1b\u0e41\u0e25\u0e49\u0e27 \u0e20\u0e32\u0e1e\u0e23\u0e27\u0e21\u0e02\u0e2d\u0e07\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e40\u0e17\u0e40\u0e25\u0e40\u0e21\u0e15\u0e34\u0e01\u0e2a\u0e4c\u0e21\u0e2d\u0e07\u0e40\u0e2b\u0e47\u0e19\u0e17\u0e32\u0e07\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e40\u0e0a\u0e48\u0e19 \u0e01\u0e32\u0e23\u0e41\u0e0a\u0e23\u0e4c\u0e23\u0e16 \u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e23\u0e16\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e19 \u0e41\u0e1c\u0e19\u0e01\u0e32\u0e23\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07 \u0e41\u0e25\u0e30\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e17\u0e32\u0e07\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e25\u0e14\u0e04\u0e48\u0e32\u0e43\u0e0a\u0e49\u0e08\u0e48\u0e32\u0e22\u0e14\u0e49\u0e32\u0e19\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e42\u0e14\u0e22\u0e23\u0e27\u0e21\u00a0<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">\u0e43\u0e19\u0e02\u0e13\u0e30\u0e17\u0e35\u0e48\u0e44\u0e27\u0e23\u0e31\u0e2a\u0e22\u0e31\u0e07\u0e04\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e41\u0e25\u0e30\u0e42\u0e25\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e15\u0e31\u0e27\u0e40\u0e02\u0e49\u0e32\u0e2a\u0e39\u0e48\u0e20\u0e32\u0e27\u0e30\u0e1b\u0e01\u0e15\u0e34\u0e43\u0e2b\u0e21\u0e48 \u0e1c\u0e39\u0e49\u0e21\u0e35\u0e2d\u0e33\u0e19\u0e32\u0e08\u0e15\u0e31\u0e14\u0e2a\u0e34\u0e19\u0e43\u0e08\u0e43\u0e19\u0e15\u0e25\u0e32\u0e14\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e08\u0e33\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e2d\u0e07\u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19\u0e25\u0e48\u0e27\u0e07\u0e2b\u0e19\u0e49\u0e32\u0e42\u0e14\u0e22\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07\u0e41\u0e25\u0e30\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e15\u0e49\u0e19\u0e17\u0e38\u0e19\u0e42\u0e14\u0e22\u0e23\u0e27\u0e21\u0e02\u0e2d\u0e07\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e02\u0e2d\u0e07\u0e15\u0e19 \u0e1a\u0e32\u0e07\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e44\u0e14\u0e49\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27\u0e42\u0e14\u0e22\u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e42\u0e1b\u0e23\u0e48\u0e07\u0e43\u0e2a\u0e02\u0e2d\u0e07\u0e15\u0e49\u0e19\u0e17\u0e38\u0e19\u0e23\u0e27\u0e21\u0e43\u0e19\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e08\u0e49\u0e32\u0e02\u0e2d\u0e07\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e17\u0e35\u0e48\u0e21\u0e35\u0e2d\u0e22\u0e39\u0e48 \u0e41\u0e25\u0e30\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e1b\u0e31\u0e08\u0e08\u0e31\u0e22\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e17\u0e35\u0e48\u0e21\u0e35\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e43\u0e19\u0e01\u0e32\u0e23\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u00a0<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32\u0e01\u0e32\u0e23\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e40\u0e0a\u0e34\u0e07\u0e01\u0e25\u0e22\u0e38\u0e17\u0e18\u0e4c\u0e02\u0e2d\u0e07\u0e01\u0e2d\u0e07\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e15\u0e48\u0e2d\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e43\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e19\u0e35\u0e49\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2d\u0e22\u0e39\u0e48\u0e23\u0e2d\u0e14\u0e44\u0e14\u0e49\u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07\u0e27\u0e34\u0e01\u0e24\u0e15\u0e19\u0e35\u0e49 \u0e41\u0e25\u0e30\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e0a\u0e48\u0e27\u0e22\u0e43\u0e2b\u0e49\u0e1e\u0e27\u0e01\u0e40\u0e02\u0e32\u0e17\u0e33\u0e40\u0e0a\u0e48\u0e19\u0e19\u0e31\u0e49\u0e19\u0e44\u0e14\u0e49 \u0e1e\u0e27\u0e01\u0e40\u0e02\u0e32\u0e22\u0e31\u0e07\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e43\u0e0a\u0e49\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e01\u0e2d\u0e07\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e17\u0e35\u0e48\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21\u0e44\u0e14\u0e49\u0e2d\u0e35\u0e01\u0e14\u0e49\u0e27\u0e22\u00a0<a href=\"https:\/\/uffizio.com\/th\/blog\/monitor-fleet-performance-with-its-work-efficiency\/\">\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e02\u0e2d\u0e07\u0e01\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e2d<\/a>\u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e43\u0e2b\u0e49\u0e21\u0e35\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e22\u0e34\u0e48\u0e07\u0e02\u0e36\u0e49\u0e19 \u0e41\u0e25\u0e30\u0e25\u0e14\u0e15\u0e49\u0e19\u0e17\u0e38\u0e19\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e08\u0e33\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e0b\u0e49\u0e33\u0e0b\u0e49\u0e2d\u0e19\u00a0<\/p>\r\n\r\n\r\n\r\n<h3 class=\"wp-block-heading\" id=\"h-focus-on-awareness-and-efficiency\">\u0e40\u0e19\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e15\u0e23\u0e30\u0e2b\u0e19\u0e31\u0e01\u0e23\u0e39\u0e49\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e<\/h3>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">\u0e2a\u0e38\u0e20\u0e32\u0e29\u0e34\u0e15\u0e22\u0e2d\u0e14\u0e19\u0e34\u0e22\u0e21\u0e01\u0e25\u0e48\u0e32\u0e27\u0e27\u0e48\u0e32 \u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e04\u0e37\u0e2d\u0e1e\u0e25\u0e31\u0e07 \u0e41\u0e25\u0e30\u0e43\u0e19\u0e22\u0e32\u0e21\u0e27\u0e34\u0e01\u0e24\u0e15\u0e40\u0e0a\u0e48\u0e19\u0e19\u0e35\u0e49 \u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e17\u0e33\u0e44\u0e14\u0e49\u0e21\u0e32\u0e01\u0e01\u0e27\u0e48\u0e32\u0e41\u0e04\u0e48\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1e\u0e25\u0e31\u0e07\u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e21\u0e31\u0e19\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e0a\u0e48\u0e27\u0e22\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e1e\u0e27\u0e01\u0e40\u0e02\u0e32\u0e44\u0e14\u0e49\u0e08\u0e23\u0e34\u0e07 \u0e46<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">\u0e14\u0e49\u0e27\u0e22\u0e40\u0e2b\u0e15\u0e38\u0e19\u0e35\u0e49 \u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e15\u0e23\u0e30\u0e2b\u0e19\u0e31\u0e01\u0e23\u0e39\u0e49\u0e43\u0e19\u0e2b\u0e21\u0e39\u0e48\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e08\u0e36\u0e07\u0e22\u0e31\u0e07\u0e04\u0e07\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e43\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e40\u0e17\u0e40\u0e25\u0e40\u0e21\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e01\u0e32\u0e23\u0e21\u0e35\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e04\u0e23\u0e1a\u0e16\u0e49\u0e27\u0e19\u0e44\u0e21\u0e48\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e41\u0e15\u0e48\u0e08\u0e30\u0e1b\u0e01\u0e1b\u0e49\u0e2d\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13\u0e40\u0e17\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19 \u0e41\u0e15\u0e48\u0e22\u0e31\u0e07\u0e0a\u0e48\u0e27\u0e22\u0e1b\u0e01\u0e1b\u0e49\u0e2d\u0e07\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e02\u0e2d\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e23\u0e31\u0e27\u0e02\u0e2d\u0e07\u0e1e\u0e27\u0e01\u0e40\u0e02\u0e32 \u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e17\u0e38\u0e01\u0e04\u0e19\u0e17\u0e35\u0e48\u0e1e\u0e27\u0e01\u0e40\u0e02\u0e32\u0e15\u0e34\u0e14\u0e15\u0e48\u0e2d\u0e14\u0e49\u0e27\u0e22\u00a0<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">\u0e2a\u0e16\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e22\u0e31\u0e07\u0e04\u0e07\u0e40\u0e1b\u0e34\u0e14\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07\u0e01\u0e32\u0e23\u0e23\u0e30\u0e1a\u0e32\u0e14\u0e43\u0e2b\u0e0d\u0e48\u0e44\u0e14\u0e49\u0e22\u0e49\u0e33\u0e40\u0e15\u0e37\u0e2d\u0e19\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e02\u0e31\u0e1a\u0e23\u0e16\u0e41\u0e25\u0e30\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e04\u0e19\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e2b\u0e49\u0e14\u0e39\u0e41\u0e25\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e23\u0e31\u0e01\u0e29\u0e32\u0e2a\u0e38\u0e02\u0e2d\u0e19\u0e32\u0e21\u0e31\u0e22\u0e17\u0e35\u0e48\u0e14\u0e35 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49\u0e22\u0e31\u0e07\u0e44\u0e14\u0e49\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e43\u0e2b\u0e49\u0e1e\u0e27\u0e01\u0e40\u0e02\u0e32\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e15\u0e32\u0e21\u0e21\u0e32\u0e15\u0e23\u0e01\u0e32\u0e23\u0e40\u0e27\u0e49\u0e19\u0e23\u0e30\u0e22\u0e30\u0e2b\u0e48\u0e32\u0e07\u0e17\u0e32\u0e07\u0e2a\u0e31\u0e07\u0e04\u0e21 \u0e41\u0e25\u0e30\u0e40\u0e02\u0e49\u0e32\u0e43\u0e08\u0e16\u0e36\u0e07\u0e1c\u0e25\u0e01\u0e23\u0e30\u0e17\u0e1a\u0e02\u0e2d\u0e07\u0e44\u0e27\u0e23\u0e31\u0e2a\u0e15\u0e48\u0e2d\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e04\u0e19\u0e23\u0e2d\u0e1a\u0e02\u0e49\u0e32\u0e07\u0e2b\u0e32\u0e01\u0e44\u0e21\u0e48\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e15\u0e32\u0e21\u0e21\u0e32\u0e15\u0e23\u0e01\u0e32\u0e23\u0e40\u0e2b\u0e25\u0e48\u0e32\u0e19\u0e35\u0e49\u00a0<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">\u0e43\u0e19\u0e17\u0e32\u0e07\u0e01\u0e25\u0e31\u0e1a\u0e01\u0e31\u0e19 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e21\u0e31\u0e48\u0e19\u0e43\u0e08\u0e16\u0e36\u0e07\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e44\u0e14\u0e49\u0e08\u0e31\u0e14\u0e15\u0e31\u0e49\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e08\u0e32\u0e01\u0e23\u0e30\u0e22\u0e30\u0e44\u0e01\u0e25\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e01\u0e32\u0e23\u0e1d\u0e36\u0e01\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e23\u0e22\u0e32\u0e22\u0e17\u0e35\u0e48\u0e08\u0e33\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e01\u0e48\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1b\u0e23\u0e31\u0e1a\u0e15\u0e31\u0e27\u0e43\u0e2b\u0e49\u0e40\u0e02\u0e49\u0e32\u0e01\u0e31\u0e1a\u0e27\u0e34\u0e16\u0e35\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e43\u0e2b\u0e21\u0e48 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49\u0e22\u0e31\u0e07\u0e21\u0e35\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e02\u0e49\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e43\u0e2b\u0e49\u0e01\u0e33\u0e25\u0e31\u0e07\u0e43\u0e08\u0e41\u0e25\u0e30\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07\u0e40\u0e27\u0e25\u0e32\u0e17\u0e35\u0e48\u0e22\u0e32\u0e01\u0e25\u0e33\u0e1a\u0e32\u0e01\u0e19\u0e35\u0e49 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e02\u0e27\u0e31\u0e0d\u0e01\u0e33\u0e25\u0e31\u0e07\u0e43\u0e08\u0e41\u0e25\u0e30\u0e01\u0e23\u0e30\u0e15\u0e38\u0e49\u0e19\u0e43\u0e2b\u0e49\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e43\u0e19\u0e17\u0e35\u0e21\u0e21\u0e38\u0e48\u0e07\u0e21\u0e31\u0e48\u0e19\u0e15\u0e48\u0e2d\u0e44\u0e1b\u0e41\u0e21\u0e49\u0e08\u0e30\u0e40\u0e1c\u0e0a\u0e34\u0e0d\u0e01\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e17\u0e49\u0e32\u0e17\u0e32\u0e22\u0e17\u0e35\u0e48\u0e40\u0e01\u0e34\u0e14\u0e08\u0e32\u0e01\u0e27\u0e34\u0e01\u0e24\u0e15\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e42\u0e25\u0e01\u0e19\u0e35\u0e49\u00a0<\/p>\r\n\r\n\r\n\r\n<h4 class=\"wp-block-heading\" id=\"h-supporting-each-other-during-the-pandemic\">\u0e01\u0e32\u0e23\u0e0a\u0e48\u0e27\u0e22\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e0b\u0e36\u0e48\u0e07\u0e01\u0e31\u0e19\u0e41\u0e25\u0e30\u0e01\u0e31\u0e19\u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07\u0e01\u0e32\u0e23\u0e23\u0e30\u0e1a\u0e32\u0e14\u0e43\u0e2b\u0e0d\u0e48<\/h4>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e21\u0e37\u0e2d\u0e01\u0e31\u0e1a\u0e42\u0e04\u0e27\u0e34\u0e14-19 \u0e2a\u0e48\u0e07\u0e1c\u0e25\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e15\u0e49\u0e2d\u0e07\u0e40\u0e2a\u0e35\u0e22\u0e2a\u0e25\u0e30\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e21\u0e32\u0e01 \u0e41\u0e21\u0e49\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e34\u0e48\u0e07\u0e17\u0e35\u0e48\u0e04\u0e32\u0e14\u0e44\u0e21\u0e48\u0e16\u0e36\u0e07 \u0e41\u0e15\u0e48\u0e41\u0e19\u0e27\u0e42\u0e19\u0e49\u0e21\u0e43\u0e2b\u0e21\u0e48\u0e46 \u0e43\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e40\u0e17\u0e40\u0e25\u0e40\u0e21\u0e15\u0e34\u0e01\u0e2a\u0e4c\u0e19\u0e35\u0e49\u0e44\u0e14\u0e49\u0e41\u0e2a\u0e14\u0e07\u0e43\u0e2b\u0e49\u0e40\u0e2b\u0e47\u0e19\u0e16\u0e36\u0e07\u0e04\u0e27\u0e32\u0e21\u0e22\u0e37\u0e14\u0e2b\u0e22\u0e38\u0e48\u0e19\u0e02\u0e2d\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e35\u0e48\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e43\u0e19\u0e20\u0e32\u0e04\u0e2a\u0e48\u0e27\u0e19\u0e19\u0e35\u0e49 \u0e41\u0e21\u0e49\u0e08\u0e30\u0e15\u0e49\u0e2d\u0e07\u0e1b\u0e34\u0e14\u0e17\u0e33\u0e01\u0e32\u0e23\u0e0a\u0e31\u0e48\u0e27\u0e04\u0e23\u0e32\u0e27\u0e41\u0e25\u0e30\u0e16\u0e39\u0e01\u0e1c\u0e25\u0e31\u0e01\u0e14\u0e31\u0e19\u0e08\u0e19\u0e16\u0e36\u0e07\u0e02\u0e35\u0e14\u0e08\u0e33\u0e01\u0e31\u0e14 \u0e43\u0e19\u0e02\u0e13\u0e30\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e31\u0e19\u0e01\u0e47\u0e22\u0e31\u0e07\u0e04\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e2b\u0e48\u0e27\u0e07\u0e42\u0e0b\u0e48\u0e2d\u0e38\u0e1b\u0e17\u0e32\u0e19\u0e41\u0e25\u0e30\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e40\u0e2d\u0e32\u0e44\u0e27\u0e49\u0e44\u0e14\u0e49\u00a0<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">\u0e40\u0e23\u0e32\u0e02\u0e2d\u0e0a\u0e37\u0e48\u0e19\u0e0a\u0e21\u0e04\u0e27\u0e32\u0e21\u0e1e\u0e22\u0e32\u0e22\u0e32\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14\u0e17\u0e35\u0e48\u0e40\u0e23\u0e32\u0e44\u0e14\u0e49\u0e40\u0e2b\u0e47\u0e19\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e20\u0e32\u0e1e\u0e23\u0e27\u0e21\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e40\u0e17\u0e40\u0e25\u0e40\u0e21\u0e15\u0e34\u0e01\u0e2a\u0e4c\u0e04\u0e23\u0e31\u0e49\u0e07\u0e25\u0e48\u0e32\u0e2a\u0e38\u0e14 \u0e42\u0e14\u0e22\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e22\u0e34\u0e48\u0e07\u0e21\u0e32\u0e15\u0e23\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e21\u0e38\u0e48\u0e07\u0e40\u0e1b\u0e49\u0e32\u0e44\u0e1b\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e1b\u0e01\u0e1b\u0e49\u0e2d\u0e07\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e41\u0e25\u0e30\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e23\u0e48\u0e23\u0e30\u0e1a\u0e32\u0e14\u0e02\u0e2d\u0e07\u0e44\u0e27\u0e23\u0e31\u0e2a \u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07\u0e40\u0e27\u0e25\u0e32\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e40\u0e04\u0e22\u0e40\u0e01\u0e34\u0e14\u0e02\u0e36\u0e49\u0e19\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e19\u0e19\u0e35\u0e49 \u0e40\u0e23\u0e32\u0e02\u0e2d\u0e0a\u0e37\u0e48\u0e19\u0e0a\u0e21\u0e04\u0e27\u0e32\u0e21\u0e1e\u0e22\u0e32\u0e22\u0e32\u0e21\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e19\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e04\u0e07\u0e04\u0e25\u0e31\u0e07\u00a0<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">\u0e40\u0e23\u0e32\u0e08\u0e30\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e40\u0e0a\u0e48\u0e19\u0e19\u0e31\u0e49\u0e19\u0e15\u0e48\u0e2d\u0e44\u0e1b \u0e41\u0e25\u0e30\u0e41\u0e2a\u0e14\u0e07\u0e01\u0e32\u0e23\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e02\u0e2d\u0e07\u0e40\u0e23\u0e32\u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e40\u0e17\u0e40\u0e25\u0e40\u0e21\u0e15\u0e34\u0e01\u0e2a\u0e4c\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14 \u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e40\u0e1c\u0e22\u0e41\u0e1e\u0e23\u0e48\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e0b\u0e36\u0e48\u0e07\u0e08\u0e30\u0e0a\u0e48\u0e27\u0e22\u0e43\u0e2b\u0e49\u0e40\u0e23\u0e32\u0e1d\u0e48\u0e32\u0e1f\u0e31\u0e19\u0e27\u0e34\u0e01\u0e24\u0e15\u0e19\u0e35\u0e49\u0e44\u0e1b\u0e14\u0e49\u0e27\u0e22\u0e01\u0e31\u0e19\u00a0<\/p>","protected":false},"excerpt":{"rendered":"<p>Business must continue even if the world is dealing with the coronavirus pandemic. Operating under no ifs and no buts, various sectors across the globe have adopted remote working strategies to their operations in order for them to thrive despite the crisis. The global telematics market is no exception to the effects of COVID-19, with [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":9908,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[29],"tags":[46],"class_list":["post-2403","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","tag-latest-update"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>How Telematics Industry Has Changed during the Pandemic - Uffizio<\/title>\n<meta name=\"description\" content=\"Know how the global telematics industry during the COVID-19 pandemic has seen a drastic fall in the automotive industry.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/uffizio.com\/th\/blog\/how-telematics-industry-has-changed-during-the-pandemic\/\" \/>\n<meta property=\"og:locale\" content=\"th_TH\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"How Telematics Industry Has Changed during the Pandemic\" \/>\n<meta property=\"og:description\" content=\"Know how the global telematics industry during the COVID-19 pandemic has seen a drastic fall in the automotive industry.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/uffizio.com\/th\/blog\/how-telematics-industry-has-changed-during-the-pandemic\/\" \/>\n<meta property=\"og:site_name\" content=\"Uffizio\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-08T07:19:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-22T06:28:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/uffizio.com\/wp-content\/uploads\/2020\/06\/telematics-fleet-1-1024x683-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"uffizio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"uffizio\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 \u0e19\u0e32\u0e17\u0e35\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/uffizio.com\\\/th\\\/blog\\\/how-telematics-industry-has-changed-during-the-pandemic\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/uffizio.com\\\/th\\\/blog\\\/how-telematics-industry-has-changed-during-the-pandemic\\\/\"},\"author\":{\"name\":\"uffizio\",\"@id\":\"https:\\\/\\\/uffizio.com\\\/th\\\/#\\\/schema\\\/person\\\/5475a82825addfcc6485fb7ddc195eba\"},\"headline\":\"How Telematics Industry Has Changed during the Pandemic\",\"datePublished\":\"2020-06-08T07:19:47+00:00\",\"dateModified\":\"2026-05-22T06:28:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/uffizio.com\\\/th\\\/blog\\\/how-telematics-industry-has-changed-during-the-pandemic\\\/\"},\"wordCount\":1353,\"publisher\":{\"@id\":\"https:\\\/\\\/uffizio.com\\\/th\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/uffizio.com\\\/th\\\/blog\\\/how-telematics-industry-has-changed-during-the-pandemic\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/uffizio.com\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/telematics-fleet-1-1024x683-1.jpg\",\"keywords\":[\"Latest Update\"],\"articleSection\":[\"Blog\"],\"inLanguage\":\"th\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/uffizio.com\\\/th\\\/blog\\\/how-telematics-industry-has-changed-during-the-pandemic\\\/\",\"url\":\"https:\\\/\\\/uffizio.com\\\/th\\\/blog\\\/how-telematics-industry-has-changed-during-the-pandemic\\\/\",\"name\":\"How Telematics Industry Has Changed during the Pandemic - Uffizio\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/uffizio.com\\\/th\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/uffizio.com\\\/th\\\/blog\\\/how-telematics-industry-has-changed-during-the-pandemic\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/uffizio.com\\\/th\\\/blog\\\/how-telematics-industry-has-changed-during-the-pandemic\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/uffizio.com\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/telematics-fleet-1-1024x683-1.jpg\",\"datePublished\":\"2020-06-08T07:19:47+00:00\",\"dateModified\":\"2026-05-22T06:28:12+00:00\",\"description\":\"Know how the global telematics industry during the COVID-19 pandemic has seen a drastic fall in the automotive industry.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/uffizio.com\\\/th\\\/blog\\\/how-telematics-industry-has-changed-during-the-pandemic\\\/#breadcrumb\"},\"inLanguage\":\"th\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/uffizio.com\\\/th\\\/blog\\\/how-telematics-industry-has-changed-during-the-pandemic\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\\\/\\\/uffizio.com\\\/th\\\/blog\\\/how-telematics-industry-has-changed-during-the-pandemic\\\/#primaryimage\",\"url\":\"https:\\\/\\\/uffizio.com\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/telematics-fleet-1-1024x683-1.jpg\",\"contentUrl\":\"https:\\\/\\\/uffizio.com\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/telematics-fleet-1-1024x683-1.jpg\",\"width\":1024,\"height\":683,\"caption\":\"telematics-fleet-1-1024x683-1\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/uffizio.com\\\/th\\\/blog\\\/how-telematics-industry-has-changed-during-the-pandemic\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/uffizio.com\\\/th\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"How Telematics Industry Has Changed during the Pandemic\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/uffizio.com\\\/th\\\/#website\",\"url\":\"https:\\\/\\\/uffizio.com\\\/th\\\/\",\"name\":\"Uffizio\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/uffizio.com\\\/th\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/uffizio.com\\\/th\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"th\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/uffizio.com\\\/th\\\/#organization\",\"name\":\"Uffizio\",\"url\":\"https:\\\/\\\/uffizio.com\\\/th\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\\\/\\\/uffizio.com\\\/th\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/uffizio.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Uffizio-logo.svg\",\"contentUrl\":\"https:\\\/\\\/uffizio.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Uffizio-logo.svg\",\"width\":237,\"height\":35,\"caption\":\"Uffizio\"},\"image\":{\"@id\":\"https:\\\/\\\/uffizio.com\\\/th\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/uffizio.com\\\/th\\\/#\\\/schema\\\/person\\\/5475a82825addfcc6485fb7ddc195eba\",\"name\":\"uffizio\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b77738c65df96915961877b1a9ce793a765d3357a4af4204e5d8c3416f362ce6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b77738c65df96915961877b1a9ce793a765d3357a4af4204e5d8c3416f362ce6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b77738c65df96915961877b1a9ce793a765d3357a4af4204e5d8c3416f362ce6?s=96&d=mm&r=g\",\"caption\":\"uffizio\"},\"sameAs\":[\"https:\\\/\\\/uffizio.com\\\/th\\\/\"],\"url\":\"https:\\\/\\\/uffizio.com\\\/th\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"How Telematics Industry Has Changed during the Pandemic - Uffizio","description":"Know how the global telematics industry during the COVID-19 pandemic has seen a drastic fall in the automotive industry.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/uffizio.com\/th\/blog\/how-telematics-industry-has-changed-during-the-pandemic\/","og_locale":"th_TH","og_type":"article","og_title":"How Telematics Industry Has Changed during the Pandemic","og_description":"Know how the global telematics industry during the COVID-19 pandemic has seen a drastic fall in the automotive industry.","og_url":"https:\/\/uffizio.com\/th\/blog\/how-telematics-industry-has-changed-during-the-pandemic\/","og_site_name":"Uffizio","article_published_time":"2020-06-08T07:19:47+00:00","article_modified_time":"2026-05-22T06:28:12+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/uffizio.com\/wp-content\/uploads\/2020\/06\/telematics-fleet-1-1024x683-1.jpg","type":"image\/jpeg"}],"author":"uffizio","twitter_card":"summary_large_image","twitter_misc":{"Written by":"uffizio","Est. reading time":"7 \u0e19\u0e32\u0e17\u0e35"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/uffizio.com\/th\/blog\/how-telematics-industry-has-changed-during-the-pandemic\/#article","isPartOf":{"@id":"https:\/\/uffizio.com\/th\/blog\/how-telematics-industry-has-changed-during-the-pandemic\/"},"author":{"name":"uffizio","@id":"https:\/\/uffizio.com\/th\/#\/schema\/person\/5475a82825addfcc6485fb7ddc195eba"},"headline":"How Telematics Industry Has Changed during the Pandemic","datePublished":"2020-06-08T07:19:47+00:00","dateModified":"2026-05-22T06:28:12+00:00","mainEntityOfPage":{"@id":"https:\/\/uffizio.com\/th\/blog\/how-telematics-industry-has-changed-during-the-pandemic\/"},"wordCount":1353,"publisher":{"@id":"https:\/\/uffizio.com\/th\/#organization"},"image":{"@id":"https:\/\/uffizio.com\/th\/blog\/how-telematics-industry-has-changed-during-the-pandemic\/#primaryimage"},"thumbnailUrl":"https:\/\/uffizio.com\/wp-content\/uploads\/2020\/06\/telematics-fleet-1-1024x683-1.jpg","keywords":["Latest Update"],"articleSection":["Blog"],"inLanguage":"th"},{"@type":"WebPage","@id":"https:\/\/uffizio.com\/th\/blog\/how-telematics-industry-has-changed-during-the-pandemic\/","url":"https:\/\/uffizio.com\/th\/blog\/how-telematics-industry-has-changed-during-the-pandemic\/","name":"How Telematics Industry Has Changed during the Pandemic - Uffizio","isPartOf":{"@id":"https:\/\/uffizio.com\/th\/#website"},"primaryImageOfPage":{"@id":"https:\/\/uffizio.com\/th\/blog\/how-telematics-industry-has-changed-during-the-pandemic\/#primaryimage"},"image":{"@id":"https:\/\/uffizio.com\/th\/blog\/how-telematics-industry-has-changed-during-the-pandemic\/#primaryimage"},"thumbnailUrl":"https:\/\/uffizio.com\/wp-content\/uploads\/2020\/06\/telematics-fleet-1-1024x683-1.jpg","datePublished":"2020-06-08T07:19:47+00:00","dateModified":"2026-05-22T06:28:12+00:00","description":"Know how the global telematics industry during the COVID-19 pandemic has seen a drastic fall in the automotive industry.","breadcrumb":{"@id":"https:\/\/uffizio.com\/th\/blog\/how-telematics-industry-has-changed-during-the-pandemic\/#breadcrumb"},"inLanguage":"th","potentialAction":[{"@type":"ReadAction","target":["https:\/\/uffizio.com\/th\/blog\/how-telematics-industry-has-changed-during-the-pandemic\/"]}]},{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/uffizio.com\/th\/blog\/how-telematics-industry-has-changed-during-the-pandemic\/#primaryimage","url":"https:\/\/uffizio.com\/wp-content\/uploads\/2020\/06\/telematics-fleet-1-1024x683-1.jpg","contentUrl":"https:\/\/uffizio.com\/wp-content\/uploads\/2020\/06\/telematics-fleet-1-1024x683-1.jpg","width":1024,"height":683,"caption":"telematics-fleet-1-1024x683-1"},{"@type":"BreadcrumbList","@id":"https:\/\/uffizio.com\/th\/blog\/how-telematics-industry-has-changed-during-the-pandemic\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/uffizio.com\/th\/"},{"@type":"ListItem","position":2,"name":"How Telematics Industry Has Changed during the Pandemic"}]},{"@type":"WebSite","@id":"https:\/\/uffizio.com\/th\/#website","url":"https:\/\/uffizio.com\/th\/","name":"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19","description":"","publisher":{"@id":"https:\/\/uffizio.com\/th\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/uffizio.com\/th\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"th"},{"@type":"Organization","@id":"https:\/\/uffizio.com\/th\/#organization","name":"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19","url":"https:\/\/uffizio.com\/th\/","logo":{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/uffizio.com\/th\/#\/schema\/logo\/image\/","url":"https:\/\/uffizio.com\/wp-content\/uploads\/2025\/10\/Uffizio-logo.svg","contentUrl":"https:\/\/uffizio.com\/wp-content\/uploads\/2025\/10\/Uffizio-logo.svg","width":237,"height":35,"caption":"Uffizio"},"image":{"@id":"https:\/\/uffizio.com\/th\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/uffizio.com\/th\/#\/schema\/person\/5475a82825addfcc6485fb7ddc195eba","name":"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19","image":{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/secure.gravatar.com\/avatar\/b77738c65df96915961877b1a9ce793a765d3357a4af4204e5d8c3416f362ce6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b77738c65df96915961877b1a9ce793a765d3357a4af4204e5d8c3416f362ce6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b77738c65df96915961877b1a9ce793a765d3357a4af4204e5d8c3416f362ce6?s=96&d=mm&r=g","caption":"uffizio"},"sameAs":["https:\/\/uffizio.com\/th\/"],"url":"https:\/\/uffizio.com\/th\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/uffizio.com\/th\/wp-json\/wp\/v2\/posts\/2403","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/uffizio.com\/th\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/uffizio.com\/th\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/uffizio.com\/th\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/uffizio.com\/th\/wp-json\/wp\/v2\/comments?post=2403"}],"version-history":[{"count":0,"href":"https:\/\/uffizio.com\/th\/wp-json\/wp\/v2\/posts\/2403\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/uffizio.com\/th\/wp-json\/wp\/v2\/media\/9908"}],"wp:attachment":[{"href":"https:\/\/uffizio.com\/th\/wp-json\/wp\/v2\/media?parent=2403"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/uffizio.com\/th\/wp-json\/wp\/v2\/categories?post=2403"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/uffizio.com\/th\/wp-json\/wp\/v2\/tags?post=2403"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}