{"id":3851,"date":"2019-07-09T11:35:42","date_gmt":"2019-07-09T11:35:42","guid":{"rendered":"https:\/\/www.uffizio.com\/?p=3851"},"modified":"2026-05-20T04:47:20","modified_gmt":"2026-05-20T04:47:20","slug":"trakzee-payment-gateway-easy-and-secure","status":"publish","type":"post","link":"https:\/\/uffizio.com\/pt\/blog\/trakzee-payment-gateway-easy-and-secure\/","title":{"rendered":"Portal de pagamentos Trakzee. F\u00e1cil e seguro."},"content":{"rendered":"<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"970\" height=\"507\" class=\"wp-image-3852\" src=\"https:\/\/www.uffizio.com\/wp-content\/uploads\/2022\/06\/trakzee-payment.jpg\" alt=\"trakzee-payment\" srcset=\"https:\/\/uffizio.com\/wp-content\/uploads\/2022\/06\/trakzee-payment.jpg 970w, https:\/\/uffizio.com\/wp-content\/uploads\/2022\/06\/trakzee-payment-300x157.jpg 300w, https:\/\/uffizio.com\/wp-content\/uploads\/2022\/06\/trakzee-payment-768x401.jpg 768w\" sizes=\"(max-width: 970px) 100vw, 970px\" \/><\/figure>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Diariamente, deparamo-nos com diversas op\u00e7\u00f5es de pagamento, como dinheiro em numer\u00e1rio, online, d\u00e9bito ou cheque. Atualmente, a op\u00e7\u00e3o de pagamento mais popular s\u00e3o as carteiras e gateways digitais. Trata-se de um m\u00e9todo r\u00e1pido e f\u00e1cil para efetuar pagamentos. A raz\u00e3o do seu sucesso \u00e9 a capacidade de realizar qualquer pagamento a partir de qualquer lugar e a qualquer momento.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Este artigo abordou as op\u00e7\u00f5es de pagamento dispon\u00edveis para si. Aqui, falaremos sobre o m\u00f3dulo de pagamento do Trakzee e os seus benef\u00edcios.<\/p>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\"><strong>M\u00f3dulo de pagamento da Trakzee<\/strong><\/h2>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.uffizio-telematics.com\/\/fleet-management-software\/\">Trakzee<\/a> tem vindo a oferecer diversos recursos para auxiliar na gest\u00e3o da sua frota. Al\u00e9m disso, \u00e9 agora poss\u00edvel gerir todos os detalhes de administra\u00e7\u00e3o, revendedores, empresas e objetos.\u00a0<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Tudo o que usamos tem um pre\u00e7o, e o Trakzee n\u00e3o \u00e9 exce\u00e7\u00e3o. \u00c9 como se fosse uma cadeia de pagamentos. A empresa paga a um revendedor, e o revendedor paga a administra\u00e7\u00e3o. Para gerir isso, o nosso m\u00f3dulo de pagamentos \u00e9 muito \u00fatil.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Os utilizadores com n\u00edvel de Administrador ou Revendedor t\u00eam a op\u00e7\u00e3o de adicionar gateways de pagamento \u00e0s suas contas para que os seus subutilizadores possam efetuar pagamentos online. A Trakzee tamb\u00e9m oferece a op\u00e7\u00e3o de atualizar os pagamentos offline.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Do pagamento \u00e0 gera\u00e7\u00e3o de faturas, da cobran\u00e7a \u00e0 gest\u00e3o de relat\u00f3rios, obt\u00e9m todos os detalhes numa \u00fanica plataforma.<\/p>\r\n\r\n\r\n\r\n<h3 class=\"wp-block-heading\"><strong>Como usar?<\/strong><\/h3>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Vejamos alguns passos e op\u00e7\u00f5es do m\u00f3dulo de pagamento.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Na conta de revendedor ou administrador, pode adicionar os seus dados de pagamento. Escolha o seu gateway de pagamento e adicione os detalhes. \u00a0<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Um utilizador pode adicionar o seu plano tarif\u00e1rio para o revendedor, empresa ou objeto. Adicione os detalhes do plano tarif\u00e1rio. Aqui pode copiar os detalhes de outro plano tarif\u00e1rio, selecionando \"copiar de\". Pode definir o per\u00edodo de suspens\u00e3o da conta do subutilizador sem carregamento.\u00a0<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Pode adicionar os custos do item espec\u00edfico. Al\u00e9m disso, podemos definir taxas e impostos adicionais para esse artigo.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">A op\u00e7\u00e3o \u201cDesativar objetos\u201d no m\u00f3dulo de fatura\u00e7\u00e3o permite a utiliza\u00e7\u00e3o do objeto sem custos. Esta op\u00e7\u00e3o \u00e9 \u00fatil quando se utiliza o objeto para um teste, uma vez que, neste plano tarif\u00e1rio, o objeto n\u00e3o ser\u00e1 criado.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Para efetuar um pagamento ao utilizador respons\u00e1vel, basta clicar na carteira na plataforma e seguir os passos necess\u00e1rios.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">\u00a0Agora vamos ver como gerir pagamentos offline. Introduza os detalhes do pagamento offline no saldo, nas informa\u00e7\u00f5es espec\u00edficas do utilizador. Nestas op\u00e7\u00f5es, s\u00e3o utilizados dinheiro em numer\u00e1rio e cheques.\u00a0<\/p>\r\n\r\n\r\n\r\n<h3 class=\"wp-block-heading\"><strong>Benef\u00edcios<\/strong><\/h3>\r\n\r\n\r\n\r\n<ul class=\"wp-block-list\">\r\n<li>Diferentes utilizadores podem efetuar pagamentos online aos seus utilizadores pais.<\/li>\r\n<li>Pague com o m\u00e9todo p\u00f3s-pago ou pr\u00e9-pago<\/li>\r\n<li>Conhe\u00e7a os dados de cr\u00e9dito e d\u00e9bito do seu saldo.\u00a0<\/li>\r\n<li>Extend user&#8217;s plan for a few more days without recharging with a few easy steps<\/li>\r\n<li>Receba o restante pagamento antes do vencimento.<\/li>\r\n<li>Descarregue qualquer relat\u00f3rio em formato XLS e PDF.<\/li>\r\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Daily we come across many payment options like cash, online, debit, or cheque. Nowadays, the trending payment option is e-wallets and gateways. It\u2019s a quick and easy method of paying the expense. The reason for its success is its ability to fulfill any payment from anywhere at any time. This was about the payment options [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3852,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[29],"tags":[35],"class_list":["post-3851","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","tag-fleet-management"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Trakzee Payment Gateway. Easy and Secure<\/title>\n<meta name=\"description\" content=\"When we are moving to the digital world. Trakzee has come up with payment gateway to manage payment between user and parent user.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/uffizio.com\/pt\/blog\/trakzee-payment-gateway-easy-and-secure\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trakzee Payment Gateway. Easy and Secure\" \/>\n<meta property=\"og:description\" content=\"When we are moving to the digital world. Trakzee has come up with payment gateway to manage payment between user and parent user.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/uffizio.com\/pt\/blog\/trakzee-payment-gateway-easy-and-secure\/\" \/>\n<meta property=\"og:site_name\" content=\"Uffizio\" \/>\n<meta property=\"article:published_time\" content=\"2019-07-09T11:35:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-20T04:47:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/uffizio.com\/wp-content\/uploads\/2022\/06\/trakzee-payment.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"970\" \/>\n\t<meta property=\"og:image:height\" content=\"507\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"uffizio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"uffizio\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/uffizio.com\\\/pt\\\/blog\\\/trakzee-payment-gateway-easy-and-secure\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/uffizio.com\\\/pt\\\/blog\\\/trakzee-payment-gateway-easy-and-secure\\\/\"},\"author\":{\"name\":\"uffizio\",\"@id\":\"https:\\\/\\\/uffizio.com\\\/pt\\\/#\\\/schema\\\/person\\\/5475a82825addfcc6485fb7ddc195eba\"},\"headline\":\"Trakzee Payment Gateway. Easy and Secure\",\"datePublished\":\"2019-07-09T11:35:42+00:00\",\"dateModified\":\"2026-05-20T04:47:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/uffizio.com\\\/pt\\\/blog\\\/trakzee-payment-gateway-easy-and-secure\\\/\"},\"wordCount\":457,\"publisher\":{\"@id\":\"https:\\\/\\\/uffizio.com\\\/pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/uffizio.com\\\/pt\\\/blog\\\/trakzee-payment-gateway-easy-and-secure\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/uffizio.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/trakzee-payment.jpg\",\"keywords\":[\"Fleet Management\"],\"articleSection\":[\"Blog\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/uffizio.com\\\/pt\\\/blog\\\/trakzee-payment-gateway-easy-and-secure\\\/\",\"url\":\"https:\\\/\\\/uffizio.com\\\/pt\\\/blog\\\/trakzee-payment-gateway-easy-and-secure\\\/\",\"name\":\"Trakzee Payment Gateway. Easy and Secure\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/uffizio.com\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/uffizio.com\\\/pt\\\/blog\\\/trakzee-payment-gateway-easy-and-secure\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/uffizio.com\\\/pt\\\/blog\\\/trakzee-payment-gateway-easy-and-secure\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/uffizio.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/trakzee-payment.jpg\",\"datePublished\":\"2019-07-09T11:35:42+00:00\",\"dateModified\":\"2026-05-20T04:47:20+00:00\",\"description\":\"When we are moving to the digital world. Trakzee has come up with payment gateway to manage payment between user and parent user.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/uffizio.com\\\/pt\\\/blog\\\/trakzee-payment-gateway-easy-and-secure\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/uffizio.com\\\/pt\\\/blog\\\/trakzee-payment-gateway-easy-and-secure\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/uffizio.com\\\/pt\\\/blog\\\/trakzee-payment-gateway-easy-and-secure\\\/#primaryimage\",\"url\":\"https:\\\/\\\/uffizio.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/trakzee-payment.jpg\",\"contentUrl\":\"https:\\\/\\\/uffizio.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/trakzee-payment.jpg\",\"width\":970,\"height\":507,\"caption\":\"trakzee-payment\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/uffizio.com\\\/pt\\\/blog\\\/trakzee-payment-gateway-easy-and-secure\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/uffizio.com\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Trakzee Payment Gateway. Easy and Secure\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/uffizio.com\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/uffizio.com\\\/pt\\\/\",\"name\":\"Uffizio\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/uffizio.com\\\/pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/uffizio.com\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/uffizio.com\\\/pt\\\/#organization\",\"name\":\"Uffizio\",\"url\":\"https:\\\/\\\/uffizio.com\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/uffizio.com\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/uffizio.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Uffizio-logo.svg\",\"contentUrl\":\"https:\\\/\\\/uffizio.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Uffizio-logo.svg\",\"width\":237,\"height\":35,\"caption\":\"Uffizio\"},\"image\":{\"@id\":\"https:\\\/\\\/uffizio.com\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/uffizio.com\\\/pt\\\/#\\\/schema\\\/person\\\/5475a82825addfcc6485fb7ddc195eba\",\"name\":\"uffizio\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b77738c65df96915961877b1a9ce793a765d3357a4af4204e5d8c3416f362ce6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b77738c65df96915961877b1a9ce793a765d3357a4af4204e5d8c3416f362ce6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b77738c65df96915961877b1a9ce793a765d3357a4af4204e5d8c3416f362ce6?s=96&d=mm&r=g\",\"caption\":\"uffizio\"},\"sameAs\":[\"https:\\\/\\\/uffizio.com\\\/pt\\\/\"],\"url\":\"https:\\\/\\\/uffizio.com\\\/pt\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Portal de pagamentos Trakzee. F\u00e1cil e seguro.","description":"When we are moving to the digital world. Trakzee has come up with payment gateway to manage payment between user and parent user.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/uffizio.com\/pt\/blog\/trakzee-payment-gateway-easy-and-secure\/","og_locale":"pt_PT","og_type":"article","og_title":"Trakzee Payment Gateway. Easy and Secure","og_description":"When we are moving to the digital world. Trakzee has come up with payment gateway to manage payment between user and parent user.","og_url":"https:\/\/uffizio.com\/pt\/blog\/trakzee-payment-gateway-easy-and-secure\/","og_site_name":"Uffizio","article_published_time":"2019-07-09T11:35:42+00:00","article_modified_time":"2026-05-20T04:47:20+00:00","og_image":[{"width":970,"height":507,"url":"https:\/\/uffizio.com\/wp-content\/uploads\/2022\/06\/trakzee-payment.jpg","type":"image\/jpeg"}],"author":"uffizio","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"uffizio","Tempo estimado de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/uffizio.com\/pt\/blog\/trakzee-payment-gateway-easy-and-secure\/#article","isPartOf":{"@id":"https:\/\/uffizio.com\/pt\/blog\/trakzee-payment-gateway-easy-and-secure\/"},"author":{"name":"uffizio","@id":"https:\/\/uffizio.com\/pt\/#\/schema\/person\/5475a82825addfcc6485fb7ddc195eba"},"headline":"Trakzee Payment Gateway. Easy and Secure","datePublished":"2019-07-09T11:35:42+00:00","dateModified":"2026-05-20T04:47:20+00:00","mainEntityOfPage":{"@id":"https:\/\/uffizio.com\/pt\/blog\/trakzee-payment-gateway-easy-and-secure\/"},"wordCount":457,"publisher":{"@id":"https:\/\/uffizio.com\/pt\/#organization"},"image":{"@id":"https:\/\/uffizio.com\/pt\/blog\/trakzee-payment-gateway-easy-and-secure\/#primaryimage"},"thumbnailUrl":"https:\/\/uffizio.com\/wp-content\/uploads\/2022\/06\/trakzee-payment.jpg","keywords":["Fleet Management"],"articleSection":["Blog"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/uffizio.com\/pt\/blog\/trakzee-payment-gateway-easy-and-secure\/","url":"https:\/\/uffizio.com\/pt\/blog\/trakzee-payment-gateway-easy-and-secure\/","name":"Portal de pagamentos Trakzee. F\u00e1cil e seguro.","isPartOf":{"@id":"https:\/\/uffizio.com\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/uffizio.com\/pt\/blog\/trakzee-payment-gateway-easy-and-secure\/#primaryimage"},"image":{"@id":"https:\/\/uffizio.com\/pt\/blog\/trakzee-payment-gateway-easy-and-secure\/#primaryimage"},"thumbnailUrl":"https:\/\/uffizio.com\/wp-content\/uploads\/2022\/06\/trakzee-payment.jpg","datePublished":"2019-07-09T11:35:42+00:00","dateModified":"2026-05-20T04:47:20+00:00","description":"When we are moving to the digital world. Trakzee has come up with payment gateway to manage payment between user and parent user.","breadcrumb":{"@id":"https:\/\/uffizio.com\/pt\/blog\/trakzee-payment-gateway-easy-and-secure\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/uffizio.com\/pt\/blog\/trakzee-payment-gateway-easy-and-secure\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/uffizio.com\/pt\/blog\/trakzee-payment-gateway-easy-and-secure\/#primaryimage","url":"https:\/\/uffizio.com\/wp-content\/uploads\/2022\/06\/trakzee-payment.jpg","contentUrl":"https:\/\/uffizio.com\/wp-content\/uploads\/2022\/06\/trakzee-payment.jpg","width":970,"height":507,"caption":"trakzee-payment"},{"@type":"BreadcrumbList","@id":"https:\/\/uffizio.com\/pt\/blog\/trakzee-payment-gateway-easy-and-secure\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/uffizio.com\/pt\/"},{"@type":"ListItem","position":2,"name":"Trakzee Payment Gateway. Easy and Secure"}]},{"@type":"WebSite","@id":"https:\/\/uffizio.com\/pt\/#website","url":"https:\/\/uffizio.com\/pt\/","name":"Escrit\u00f3rio","description":"","publisher":{"@id":"https:\/\/uffizio.com\/pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/uffizio.com\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/uffizio.com\/pt\/#organization","name":"Escrit\u00f3rio","url":"https:\/\/uffizio.com\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/uffizio.com\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/uffizio.com\/wp-content\/uploads\/2025\/10\/Uffizio-logo.svg","contentUrl":"https:\/\/uffizio.com\/wp-content\/uploads\/2025\/10\/Uffizio-logo.svg","width":237,"height":35,"caption":"Uffizio"},"image":{"@id":"https:\/\/uffizio.com\/pt\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/uffizio.com\/pt\/#\/schema\/person\/5475a82825addfcc6485fb7ddc195eba","name":"escrit\u00f3rio","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/b77738c65df96915961877b1a9ce793a765d3357a4af4204e5d8c3416f362ce6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b77738c65df96915961877b1a9ce793a765d3357a4af4204e5d8c3416f362ce6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b77738c65df96915961877b1a9ce793a765d3357a4af4204e5d8c3416f362ce6?s=96&d=mm&r=g","caption":"uffizio"},"sameAs":["https:\/\/uffizio.com\/pt\/"],"url":"https:\/\/uffizio.com\/pt\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/uffizio.com\/pt\/wp-json\/wp\/v2\/posts\/3851","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/uffizio.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/uffizio.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/uffizio.com\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/uffizio.com\/pt\/wp-json\/wp\/v2\/comments?post=3851"}],"version-history":[{"count":0,"href":"https:\/\/uffizio.com\/pt\/wp-json\/wp\/v2\/posts\/3851\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/uffizio.com\/pt\/wp-json\/wp\/v2\/media\/3852"}],"wp:attachment":[{"href":"https:\/\/uffizio.com\/pt\/wp-json\/wp\/v2\/media?parent=3851"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/uffizio.com\/pt\/wp-json\/wp\/v2\/categories?post=3851"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/uffizio.com\/pt\/wp-json\/wp\/v2\/tags?post=3851"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}