{"id":3985,"date":"2019-04-18T05:36:20","date_gmt":"2019-04-18T05:36:20","guid":{"rendered":"https:\/\/www.uffizio.com\/?p=3985"},"modified":"2026-05-20T05:34:51","modified_gmt":"2026-05-20T05:34:51","slug":"ticketing-system-a-user-friendly-support-service-system","status":"publish","type":"post","link":"https:\/\/uffizio.com\/es\/blog\/ticketing-system-a-user-friendly-support-service-system\/","title":{"rendered":"Sistema de emisi\u00f3n de tickets: un sistema de servicio de soporte f\u00e1cil de usar."},"content":{"rendered":"<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"970\" height=\"507\" class=\"wp-image-3991\" src=\"https:\/\/www.uffizio.com\/wp-content\/uploads\/2022\/07\/support.jpg\" alt=\"support-team\" srcset=\"https:\/\/uffizio.com\/wp-content\/uploads\/2022\/07\/support.jpg 970w, https:\/\/uffizio.com\/wp-content\/uploads\/2022\/07\/support-300x157.jpg 300w, https:\/\/uffizio.com\/wp-content\/uploads\/2022\/07\/support-768x401.jpg 768w\" sizes=\"(max-width: 970px) 100vw, 970px\" \/><\/figure>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Hoy en d\u00eda, cuando todos en el campo de la inform\u00e1tica tienen prisa por lanzar algo nuevo, y en esa prisa habr\u00e1 errores y quejas, entonces vienen los pasos para quejarse y buscar soluciones.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Pero, \u00bffue este proceso tan f\u00e1cil como decimos ahora? No, no lo fue.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Si diriges una empresa de TI y has sido cliente de empresas de software, \u00bfc\u00f3mo resolviste alg\u00fan problema de software cuando te enfrentaste a \u00e9l?\u00a0<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">\u00bfQu\u00e9 tan dif\u00edcil fue y cu\u00e1nto tiempo tom\u00f3? Quiz\u00e1s demasiado.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">\u00bfSabes cu\u00e1l era el verdadero problema?\u00a0<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Antes de que le des muchas vueltas al asunto, queremos informarte de que hemos estado utilizando el nuevo sistema de gesti\u00f3n de incidencias para ayudarte, por lo que nuestros clientes no tienen ning\u00fan problema.\u00a0<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">En muchos momentos cr\u00edticos, usted llamar\u00e1 a una persona de soporte, y es posible que est\u00e9 ocupada en ese momento, lo que retrasa a\u00fan m\u00e1s el proceso.\u00a0<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">But, before recognising the new ticketing\u00a0system\u00a0let&#8217;s understand the older method and what difficulties are we talking about?<\/p>\r\n\r\n\r\n\r\n<h3 class=\"wp-block-heading\"><strong>Problemas anteriores:<\/strong><\/h3>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Como cliente, siempre querr\u00e1s una respuesta r\u00e1pida a tu problema, pero no siempre es posible. Por eso, antes se utilizaba el sistema de formularios web.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Anteriormente, el cliente intentaba contactar con la empresa por tel\u00e9fono o correo electr\u00f3nico para presentar quejas. Para recibir asistencia, el personal le ped\u00eda al cliente que rellenara un formulario web.\u00a0<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Rellenar el formulario es una tarea que consume mucho tiempo. Incluso despu\u00e9s de enviarlo, no siempre sabr\u00e1 el estado exacto de la reclamaci\u00f3n.\u00a0<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">But it&#8217;s not always the mistake of the company as handling a form is difficult and theirs\u00a0no report is generated\u00a0which makes it difficult for the support to know your previous problems.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">En muchos momentos cr\u00edticos, llamar\u00e1s a una persona de soporte, y puede que est\u00e9 ocupada en ese momento, entonces \u00bfpara qu\u00e9 esperar mucho tiempo?\u00a0<\/p>\r\n\r\n\r\n\r\n<h3 class=\"wp-block-heading\"><strong>Nuevo sistema de venta de entradas<\/strong><\/h3>\r\n\r\n\r\n\r\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"970\" height=\"507\" class=\"wp-image-3992\" src=\"https:\/\/www.uffizio.com\/wp-content\/uploads\/2022\/07\/uffizio-support-ticket-system.jpg\" alt=\"uffizio-support-ticket-system\" srcset=\"https:\/\/uffizio.com\/wp-content\/uploads\/2022\/07\/uffizio-support-ticket-system.jpg 970w, https:\/\/uffizio.com\/wp-content\/uploads\/2022\/07\/uffizio-support-ticket-system-300x157.jpg 300w, https:\/\/uffizio.com\/wp-content\/uploads\/2022\/07\/uffizio-support-ticket-system-768x401.jpg 768w\" sizes=\"(max-width: 970px) 100vw, 970px\" \/><\/figure>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Nuestros clientes son conscientes de que\u00a0<strong>Oficina<\/strong>\u00a0has been using the ticketing system for a long time. Don&#8217;t worry if you are unaware we are here to tell you.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">El sistema de tickets es un sistema de soporte que facilita la comunicaci\u00f3n con el cliente. Como cliente, podr\u00e1 contactar f\u00e1cilmente con el personal de soporte. Al mismo tiempo, el equipo de soporte podr\u00e1 acceder al registro de su problema actual, junto con los datos de sus consultas anteriores.\u00a0<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">It doesn&#8217;t only assist the customer, but in addition, executes the work of support team. Makes it easier and the problem-solving process turns out to be more efficient.\u00a0<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Puede generar un ticket autom\u00e1ticamente mediante correo electr\u00f3nico o visitar el sitio web o la aplicaci\u00f3n para generarlo.\u00a0<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">El sistema de emisi\u00f3n de billetes tomar\u00e1 su solicitud por correo electr\u00f3nico en<strong>\u00a0support@uffizio.in<\/strong>\u00a0y generar\u00e1 autom\u00e1ticamente un ticket para sus problemas.\u00a0<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">El cliente genera un ticket para presentar su queja, y el sistema de soporte recibe el ticket junto con otros detalles del cliente.\u00a0<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Ese \u00fanico ticket permite al equipo de soporte ofrecer soluciones dentro del flujo de trabajo sistem\u00e1tico.\u00a0<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Adem\u00e1s, el cliente sabr\u00e1 qu\u00e9 persona de soporte est\u00e1 atendiendo su solicitud. Una vez finalizado el trabajo, se le notificar\u00e1 y podr\u00e1 cerrar la incidencia.\u00a0<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Si la persona que gestiona su reclamaci\u00f3n est\u00e1 ocupada, el ticket se env\u00eda a otro miembro del equipo de soporte que tenga disponibilidad. El ticket incluir\u00e1 su reclamaci\u00f3n y la fecha l\u00edmite para la resoluci\u00f3n del problema.<\/p>\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">El sistema de tickets no se utiliza exclusivamente para quejas. Tambi\u00e9n puedes generar un ticket si deseas crear una API, personalizar tu marca o si necesitas nuevas funcionalidades.<\/p>\r\n\r\n\r\n\r\n<h4 class=\"wp-block-heading\"><strong>Conclusi\u00f3n<\/strong><\/h4>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Hope you have understood about our ticketing system. So from now on whenever you have a problem or want something new don&#8217;t think much. Just generate the ticket and your problems will be resolved for sure.<\/p>","protected":false},"excerpt":{"rendered":"<p>Today, when everybody in an IT field is in a rush to bring something new and in this rush, there will be mistakes and complaints, then the steps of complaining and bringing solutions. But was this process so easy, like we are saying right now? No, it was not. If you are operating an IT\u00a0company,\u00a0and [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3991,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[29],"tags":[30],"class_list":["post-3985","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","tag-life-at-uffizio"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Ticketing System - A user-friendly support service system<\/title>\n<meta name=\"description\" content=\"Ticketing system is a user friendly support service system which helps to bring solutions to customer complaints.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/uffizio.com\/es\/blog\/ticketing-system-a-user-friendly-support-service-system\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ticketing System - A user-friendly support service system\" \/>\n<meta property=\"og:description\" content=\"Ticketing system is a user friendly support service system which helps to bring solutions to customer complaints.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/uffizio.com\/es\/blog\/ticketing-system-a-user-friendly-support-service-system\/\" \/>\n<meta property=\"og:site_name\" content=\"Uffizio\" \/>\n<meta property=\"article:published_time\" content=\"2019-04-18T05:36:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-20T05:34:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/uffizio.com\/wp-content\/uploads\/2022\/07\/support.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"970\" \/>\n\t<meta property=\"og:image:height\" content=\"507\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"uffizio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"uffizio\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/uffizio.com\\\/es\\\/blog\\\/ticketing-system-a-user-friendly-support-service-system\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/uffizio.com\\\/es\\\/blog\\\/ticketing-system-a-user-friendly-support-service-system\\\/\"},\"author\":{\"name\":\"uffizio\",\"@id\":\"https:\\\/\\\/uffizio.com\\\/es\\\/#\\\/schema\\\/person\\\/5475a82825addfcc6485fb7ddc195eba\"},\"headline\":\"Ticketing System &#8211; A user-friendly support service system\",\"datePublished\":\"2019-04-18T05:36:20+00:00\",\"dateModified\":\"2026-05-20T05:34:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/uffizio.com\\\/es\\\/blog\\\/ticketing-system-a-user-friendly-support-service-system\\\/\"},\"wordCount\":653,\"publisher\":{\"@id\":\"https:\\\/\\\/uffizio.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/uffizio.com\\\/es\\\/blog\\\/ticketing-system-a-user-friendly-support-service-system\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/uffizio.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/support.jpg\",\"keywords\":[\"Life at Uffizio\"],\"articleSection\":[\"Blog\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/uffizio.com\\\/es\\\/blog\\\/ticketing-system-a-user-friendly-support-service-system\\\/\",\"url\":\"https:\\\/\\\/uffizio.com\\\/es\\\/blog\\\/ticketing-system-a-user-friendly-support-service-system\\\/\",\"name\":\"Ticketing System - A user-friendly support service system\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/uffizio.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/uffizio.com\\\/es\\\/blog\\\/ticketing-system-a-user-friendly-support-service-system\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/uffizio.com\\\/es\\\/blog\\\/ticketing-system-a-user-friendly-support-service-system\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/uffizio.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/support.jpg\",\"datePublished\":\"2019-04-18T05:36:20+00:00\",\"dateModified\":\"2026-05-20T05:34:51+00:00\",\"description\":\"Ticketing system is a user friendly support service system which helps to bring solutions to customer complaints.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/uffizio.com\\\/es\\\/blog\\\/ticketing-system-a-user-friendly-support-service-system\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/uffizio.com\\\/es\\\/blog\\\/ticketing-system-a-user-friendly-support-service-system\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/uffizio.com\\\/es\\\/blog\\\/ticketing-system-a-user-friendly-support-service-system\\\/#primaryimage\",\"url\":\"https:\\\/\\\/uffizio.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/support.jpg\",\"contentUrl\":\"https:\\\/\\\/uffizio.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/support.jpg\",\"width\":970,\"height\":507,\"caption\":\"support\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/uffizio.com\\\/es\\\/blog\\\/ticketing-system-a-user-friendly-support-service-system\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/uffizio.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ticketing System &#8211; A user-friendly support service system\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/uffizio.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/uffizio.com\\\/es\\\/\",\"name\":\"Uffizio\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/uffizio.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/uffizio.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/uffizio.com\\\/es\\\/#organization\",\"name\":\"Uffizio\",\"url\":\"https:\\\/\\\/uffizio.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/uffizio.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/uffizio.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Uffizio-logo.svg\",\"contentUrl\":\"https:\\\/\\\/uffizio.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Uffizio-logo.svg\",\"width\":237,\"height\":35,\"caption\":\"Uffizio\"},\"image\":{\"@id\":\"https:\\\/\\\/uffizio.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/uffizio.com\\\/es\\\/#\\\/schema\\\/person\\\/5475a82825addfcc6485fb7ddc195eba\",\"name\":\"uffizio\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b77738c65df96915961877b1a9ce793a765d3357a4af4204e5d8c3416f362ce6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b77738c65df96915961877b1a9ce793a765d3357a4af4204e5d8c3416f362ce6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b77738c65df96915961877b1a9ce793a765d3357a4af4204e5d8c3416f362ce6?s=96&d=mm&r=g\",\"caption\":\"uffizio\"},\"sameAs\":[\"https:\\\/\\\/uffizio.com\\\/es\\\/\"],\"url\":\"https:\\\/\\\/uffizio.com\\\/es\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ticketing System - A user-friendly support service system","description":"Ticketing system is a user friendly support service system which helps to bring solutions to customer complaints.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/uffizio.com\/es\/blog\/ticketing-system-a-user-friendly-support-service-system\/","og_locale":"es_MX","og_type":"article","og_title":"Ticketing System - A user-friendly support service system","og_description":"Ticketing system is a user friendly support service system which helps to bring solutions to customer complaints.","og_url":"https:\/\/uffizio.com\/es\/blog\/ticketing-system-a-user-friendly-support-service-system\/","og_site_name":"Uffizio","article_published_time":"2019-04-18T05:36:20+00:00","article_modified_time":"2026-05-20T05:34:51+00:00","og_image":[{"width":970,"height":507,"url":"https:\/\/uffizio.com\/wp-content\/uploads\/2022\/07\/support.jpg","type":"image\/jpeg"}],"author":"uffizio","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"uffizio","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/uffizio.com\/es\/blog\/ticketing-system-a-user-friendly-support-service-system\/#article","isPartOf":{"@id":"https:\/\/uffizio.com\/es\/blog\/ticketing-system-a-user-friendly-support-service-system\/"},"author":{"name":"uffizio","@id":"https:\/\/uffizio.com\/es\/#\/schema\/person\/5475a82825addfcc6485fb7ddc195eba"},"headline":"Ticketing System &#8211; A user-friendly support service system","datePublished":"2019-04-18T05:36:20+00:00","dateModified":"2026-05-20T05:34:51+00:00","mainEntityOfPage":{"@id":"https:\/\/uffizio.com\/es\/blog\/ticketing-system-a-user-friendly-support-service-system\/"},"wordCount":653,"publisher":{"@id":"https:\/\/uffizio.com\/es\/#organization"},"image":{"@id":"https:\/\/uffizio.com\/es\/blog\/ticketing-system-a-user-friendly-support-service-system\/#primaryimage"},"thumbnailUrl":"https:\/\/uffizio.com\/wp-content\/uploads\/2022\/07\/support.jpg","keywords":["Life at Uffizio"],"articleSection":["Blog"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/uffizio.com\/es\/blog\/ticketing-system-a-user-friendly-support-service-system\/","url":"https:\/\/uffizio.com\/es\/blog\/ticketing-system-a-user-friendly-support-service-system\/","name":"Ticketing System - A user-friendly support service system","isPartOf":{"@id":"https:\/\/uffizio.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/uffizio.com\/es\/blog\/ticketing-system-a-user-friendly-support-service-system\/#primaryimage"},"image":{"@id":"https:\/\/uffizio.com\/es\/blog\/ticketing-system-a-user-friendly-support-service-system\/#primaryimage"},"thumbnailUrl":"https:\/\/uffizio.com\/wp-content\/uploads\/2022\/07\/support.jpg","datePublished":"2019-04-18T05:36:20+00:00","dateModified":"2026-05-20T05:34:51+00:00","description":"Ticketing system is a user friendly support service system which helps to bring solutions to customer complaints.","breadcrumb":{"@id":"https:\/\/uffizio.com\/es\/blog\/ticketing-system-a-user-friendly-support-service-system\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/uffizio.com\/es\/blog\/ticketing-system-a-user-friendly-support-service-system\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/uffizio.com\/es\/blog\/ticketing-system-a-user-friendly-support-service-system\/#primaryimage","url":"https:\/\/uffizio.com\/wp-content\/uploads\/2022\/07\/support.jpg","contentUrl":"https:\/\/uffizio.com\/wp-content\/uploads\/2022\/07\/support.jpg","width":970,"height":507,"caption":"support"},{"@type":"BreadcrumbList","@id":"https:\/\/uffizio.com\/es\/blog\/ticketing-system-a-user-friendly-support-service-system\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/uffizio.com\/es\/"},{"@type":"ListItem","position":2,"name":"Ticketing System &#8211; A user-friendly support service system"}]},{"@type":"WebSite","@id":"https:\/\/uffizio.com\/es\/#website","url":"https:\/\/uffizio.com\/es\/","name":"Oficina","description":"","publisher":{"@id":"https:\/\/uffizio.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/uffizio.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/uffizio.com\/es\/#organization","name":"Oficina","url":"https:\/\/uffizio.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/uffizio.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/uffizio.com\/wp-content\/uploads\/2025\/10\/Uffizio-logo.svg","contentUrl":"https:\/\/uffizio.com\/wp-content\/uploads\/2025\/10\/Uffizio-logo.svg","width":237,"height":35,"caption":"Uffizio"},"image":{"@id":"https:\/\/uffizio.com\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/uffizio.com\/es\/#\/schema\/person\/5475a82825addfcc6485fb7ddc195eba","name":"oficina","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/b77738c65df96915961877b1a9ce793a765d3357a4af4204e5d8c3416f362ce6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b77738c65df96915961877b1a9ce793a765d3357a4af4204e5d8c3416f362ce6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b77738c65df96915961877b1a9ce793a765d3357a4af4204e5d8c3416f362ce6?s=96&d=mm&r=g","caption":"uffizio"},"sameAs":["https:\/\/uffizio.com\/es\/"],"url":"https:\/\/uffizio.com\/es\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/uffizio.com\/es\/wp-json\/wp\/v2\/posts\/3985","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/uffizio.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/uffizio.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/uffizio.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/uffizio.com\/es\/wp-json\/wp\/v2\/comments?post=3985"}],"version-history":[{"count":0,"href":"https:\/\/uffizio.com\/es\/wp-json\/wp\/v2\/posts\/3985\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/uffizio.com\/es\/wp-json\/wp\/v2\/media\/3991"}],"wp:attachment":[{"href":"https:\/\/uffizio.com\/es\/wp-json\/wp\/v2\/media?parent=3985"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/uffizio.com\/es\/wp-json\/wp\/v2\/categories?post=3985"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/uffizio.com\/es\/wp-json\/wp\/v2\/tags?post=3985"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}