{"id":3728,"date":"2019-11-06T13:32:34","date_gmt":"2019-11-06T13:32:34","guid":{"rendered":"https:\/\/www.uffizio.com\/?p=3728"},"modified":"2026-05-21T10:49:53","modified_gmt":"2026-05-21T10:49:53","slug":"london-introduced-an-automatic-braking-system-in-the-tram","status":"publish","type":"post","link":"https:\/\/uffizio.com\/es\/blog\/london-introduced-an-automatic-braking-system-in-the-tram\/","title":{"rendered":"Londres introdujo un sistema de frenado autom\u00e1tico en el tranv\u00eda."},"content":{"rendered":"<p class=\"wp-block-paragraph\">El tranv\u00eda es uno de los medios de transporte p\u00fablico m\u00e1s \u00fatiles en el Reino Unido. Su uso comenz\u00f3 en 1860 en Londres, cuando eran tirados por caballos. Con el paso de los a\u00f1os, los tranv\u00edas empezaron a funcionar con vapor y, posteriormente, con electricidad.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Pero con el aumento del uso del tranv\u00eda, tambi\u00e9n aumentaron los casos de accidentes.<\/p>\r\n\r\n\r\n\r\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"590\" height=\"525\" class=\"wp-image-3730\" src=\"https:\/\/www.uffizio.com\/wp-content\/uploads\/2022\/06\/croydon-tram-derail-dead-715883_1_o.jpeg\" alt=\"train derail\" srcset=\"https:\/\/uffizio.com\/wp-content\/uploads\/2022\/06\/croydon-tram-derail-dead-715883_1_o.jpeg 590w, https:\/\/uffizio.com\/wp-content\/uploads\/2022\/06\/croydon-tram-derail-dead-715883_1_o-300x267.jpeg 300w\" sizes=\"(max-width: 590px) 100vw, 590px\" \/><\/figure>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Despu\u00e9s de la <a href=\"https:\/\/en.wikipedia.org\/wiki\/2016_Croydon_tram_derailment\">Accidente de tranv\u00eda en Croydon<\/a> En noviembre de 2016, el gobierno brit\u00e1nico decidi\u00f3 buscar una soluci\u00f3n para garantizar la seguridad p\u00fablica. Esto provoc\u00f3 la muerte de 7 personas y dej\u00f3 m\u00e1s de 60 heridos. El accidente se produjo cuando el tranv\u00eda circulaba a 70 km\/h (43,5 mph) al llegar a la curva antes de la parada de Sandilands en Croydon. Los investigadores indicaron que el l\u00edmite de velocidad en la zona era de 19 km\/h (12 mph).<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Tras una investigaci\u00f3n m\u00e1s exhaustiva, la Oficina de Investigaci\u00f3n de Accidentes Ferroviarios (RAIB, por sus siglas en ingl\u00e9s) formul\u00f3 15 recomendaciones para mejorar la seguridad, adem\u00e1s del sistema de frenado autom\u00e1tico. Otras recomendaciones inclu\u00edan la reducci\u00f3n de la velocidad, el control de la velocidad, la colocaci\u00f3n de se\u00f1ales en cada curva y la mejora del procedimiento de reclamaciones de los usuarios.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Ahora, el Reino Unido contar\u00e1 con su primer servicio de tranv\u00eda con frenado autom\u00e1tico en Londres. Estos sistemas aplicar\u00e1n autom\u00e1ticamente los frenos cuando el tranv\u00eda supere el l\u00edmite de velocidad en un lugar determinado.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Este sistema funcionar\u00e1 junto con la se\u00f1al de advertencia y el sistema de monitoreo de velocidad agregados en 2017, que se utiliza para saber sobre el <a href=\"https:\/\/uffizio.com\/es\/use-case\/improving-passenger-safety-and-comfort-through-driving-behavior\/\">Distracci\u00f3n y cansancio del conductor<\/a>.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">La RAIB tambi\u00e9n descubri\u00f3 que el conductor estaba durmiendo la siesta debido al cansancio. Esto puso de manifiesto la necesidad de encontrar una soluci\u00f3n para ayudarlo. Por ello, el gobierno instal\u00f3 un sistema de se\u00f1alizaci\u00f3n reflectante en el t\u00fanel y pint\u00f3 galones para guiar al conductor. El sistema reflectante consiste en un par de esferas reflectantes que marcan el centro de la v\u00eda para que el conductor preste atenci\u00f3n. Los galones son franjas de advertencia de seguridad pintadas de amarillo y negro.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Estas medidas de seguridad, junto con un sistema de frenado autom\u00e1tico, garantizar\u00e1n la seguridad de los pasajeros en el tranv\u00eda. Estos m\u00e9todos contribuir\u00e1n a reducir los accidentes de tranv\u00eda.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Ahora, esperemos a ver c\u00f3mo funcionan estos tranv\u00edas en Londres para conocer los resultados. Es hora de que todos los pa\u00edses del mundo adopten soluciones similares o mejores para la seguridad del transporte p\u00fablico.<\/p>","protected":false},"excerpt":{"rendered":"<p>Tram is one of the most useful modes of public transport in the UK. The usage of trams began in 1860 in London, the horses drew these trams. With the passing of years, trams started running with steam and then with electricity. But with the increase in usage of Tram, the accident cases also increased. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3729,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[29],"tags":[34],"class_list":["post-3728","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","tag-telematics"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>London introduced an automatic braking system in the tram<\/title>\n<meta name=\"description\" content=\"London is soon going to run its tram with an automatic braking system. It&#039;s time for you to know why and how this idea came to implementation.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/uffizio.com\/es\/blog\/london-introduced-an-automatic-braking-system-in-the-tram\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"London introduced an automatic braking system in the tram\" \/>\n<meta property=\"og:description\" content=\"London is soon going to run its tram with an automatic braking system. It&#039;s time for you to know why and how this idea came to implementation.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/uffizio.com\/es\/blog\/london-introduced-an-automatic-braking-system-in-the-tram\/\" \/>\n<meta property=\"og:site_name\" content=\"Uffizio\" \/>\n<meta property=\"article:published_time\" content=\"2019-11-06T13:32:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-21T10:49:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/uffizio.com\/wp-content\/uploads\/2022\/06\/traminlondon_0_o.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"uffizio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"uffizio\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/uffizio.com\\\/es\\\/blog\\\/london-introduced-an-automatic-braking-system-in-the-tram\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/uffizio.com\\\/es\\\/blog\\\/london-introduced-an-automatic-braking-system-in-the-tram\\\/\"},\"author\":{\"name\":\"uffizio\",\"@id\":\"https:\\\/\\\/uffizio.com\\\/es\\\/#\\\/schema\\\/person\\\/5475a82825addfcc6485fb7ddc195eba\"},\"headline\":\"London introduced an automatic braking system in the tram\",\"datePublished\":\"2019-11-06T13:32:34+00:00\",\"dateModified\":\"2026-05-21T10:49:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/uffizio.com\\\/es\\\/blog\\\/london-introduced-an-automatic-braking-system-in-the-tram\\\/\"},\"wordCount\":366,\"publisher\":{\"@id\":\"https:\\\/\\\/uffizio.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/uffizio.com\\\/es\\\/blog\\\/london-introduced-an-automatic-braking-system-in-the-tram\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/uffizio.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/traminlondon_0_o.jpeg\",\"keywords\":[\"Telematics\"],\"articleSection\":[\"Blog\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/uffizio.com\\\/es\\\/blog\\\/london-introduced-an-automatic-braking-system-in-the-tram\\\/\",\"url\":\"https:\\\/\\\/uffizio.com\\\/es\\\/blog\\\/london-introduced-an-automatic-braking-system-in-the-tram\\\/\",\"name\":\"London introduced an automatic braking system in the tram\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/uffizio.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/uffizio.com\\\/es\\\/blog\\\/london-introduced-an-automatic-braking-system-in-the-tram\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/uffizio.com\\\/es\\\/blog\\\/london-introduced-an-automatic-braking-system-in-the-tram\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/uffizio.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/traminlondon_0_o.jpeg\",\"datePublished\":\"2019-11-06T13:32:34+00:00\",\"dateModified\":\"2026-05-21T10:49:53+00:00\",\"description\":\"London is soon going to run its tram with an automatic braking system. It's time for you to know why and how this idea came to implementation.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/uffizio.com\\\/es\\\/blog\\\/london-introduced-an-automatic-braking-system-in-the-tram\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/uffizio.com\\\/es\\\/blog\\\/london-introduced-an-automatic-braking-system-in-the-tram\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/uffizio.com\\\/es\\\/blog\\\/london-introduced-an-automatic-braking-system-in-the-tram\\\/#primaryimage\",\"url\":\"https:\\\/\\\/uffizio.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/traminlondon_0_o.jpeg\",\"contentUrl\":\"https:\\\/\\\/uffizio.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/traminlondon_0_o.jpeg\",\"width\":1280,\"height\":720,\"caption\":\"traminlondon_0_o\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/uffizio.com\\\/es\\\/blog\\\/london-introduced-an-automatic-braking-system-in-the-tram\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/uffizio.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"London introduced an automatic braking system in the tram\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/uffizio.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/uffizio.com\\\/es\\\/\",\"name\":\"Uffizio\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/uffizio.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/uffizio.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/uffizio.com\\\/es\\\/#organization\",\"name\":\"Uffizio\",\"url\":\"https:\\\/\\\/uffizio.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/uffizio.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/uffizio.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Uffizio-logo.svg\",\"contentUrl\":\"https:\\\/\\\/uffizio.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Uffizio-logo.svg\",\"width\":237,\"height\":35,\"caption\":\"Uffizio\"},\"image\":{\"@id\":\"https:\\\/\\\/uffizio.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/uffizio.com\\\/es\\\/#\\\/schema\\\/person\\\/5475a82825addfcc6485fb7ddc195eba\",\"name\":\"uffizio\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b77738c65df96915961877b1a9ce793a765d3357a4af4204e5d8c3416f362ce6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b77738c65df96915961877b1a9ce793a765d3357a4af4204e5d8c3416f362ce6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b77738c65df96915961877b1a9ce793a765d3357a4af4204e5d8c3416f362ce6?s=96&d=mm&r=g\",\"caption\":\"uffizio\"},\"sameAs\":[\"https:\\\/\\\/uffizio.com\\\/es\\\/\"],\"url\":\"https:\\\/\\\/uffizio.com\\\/es\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Londres introdujo un sistema de frenado autom\u00e1tico en el tranv\u00eda.","description":"London is soon going to run its tram with an automatic braking system. It's time for you to know why and how this idea came to implementation.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/uffizio.com\/es\/blog\/london-introduced-an-automatic-braking-system-in-the-tram\/","og_locale":"es_MX","og_type":"article","og_title":"London introduced an automatic braking system in the tram","og_description":"London is soon going to run its tram with an automatic braking system. It's time for you to know why and how this idea came to implementation.","og_url":"https:\/\/uffizio.com\/es\/blog\/london-introduced-an-automatic-braking-system-in-the-tram\/","og_site_name":"Uffizio","article_published_time":"2019-11-06T13:32:34+00:00","article_modified_time":"2026-05-21T10:49:53+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/uffizio.com\/wp-content\/uploads\/2022\/06\/traminlondon_0_o.jpeg","type":"image\/jpeg"}],"author":"uffizio","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"uffizio","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/uffizio.com\/es\/blog\/london-introduced-an-automatic-braking-system-in-the-tram\/#article","isPartOf":{"@id":"https:\/\/uffizio.com\/es\/blog\/london-introduced-an-automatic-braking-system-in-the-tram\/"},"author":{"name":"uffizio","@id":"https:\/\/uffizio.com\/es\/#\/schema\/person\/5475a82825addfcc6485fb7ddc195eba"},"headline":"London introduced an automatic braking system in the tram","datePublished":"2019-11-06T13:32:34+00:00","dateModified":"2026-05-21T10:49:53+00:00","mainEntityOfPage":{"@id":"https:\/\/uffizio.com\/es\/blog\/london-introduced-an-automatic-braking-system-in-the-tram\/"},"wordCount":366,"publisher":{"@id":"https:\/\/uffizio.com\/es\/#organization"},"image":{"@id":"https:\/\/uffizio.com\/es\/blog\/london-introduced-an-automatic-braking-system-in-the-tram\/#primaryimage"},"thumbnailUrl":"https:\/\/uffizio.com\/wp-content\/uploads\/2022\/06\/traminlondon_0_o.jpeg","keywords":["Telematics"],"articleSection":["Blog"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/uffizio.com\/es\/blog\/london-introduced-an-automatic-braking-system-in-the-tram\/","url":"https:\/\/uffizio.com\/es\/blog\/london-introduced-an-automatic-braking-system-in-the-tram\/","name":"Londres introdujo un sistema de frenado autom\u00e1tico en el tranv\u00eda.","isPartOf":{"@id":"https:\/\/uffizio.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/uffizio.com\/es\/blog\/london-introduced-an-automatic-braking-system-in-the-tram\/#primaryimage"},"image":{"@id":"https:\/\/uffizio.com\/es\/blog\/london-introduced-an-automatic-braking-system-in-the-tram\/#primaryimage"},"thumbnailUrl":"https:\/\/uffizio.com\/wp-content\/uploads\/2022\/06\/traminlondon_0_o.jpeg","datePublished":"2019-11-06T13:32:34+00:00","dateModified":"2026-05-21T10:49:53+00:00","description":"London is soon going to run its tram with an automatic braking system. It's time for you to know why and how this idea came to implementation.","breadcrumb":{"@id":"https:\/\/uffizio.com\/es\/blog\/london-introduced-an-automatic-braking-system-in-the-tram\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/uffizio.com\/es\/blog\/london-introduced-an-automatic-braking-system-in-the-tram\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/uffizio.com\/es\/blog\/london-introduced-an-automatic-braking-system-in-the-tram\/#primaryimage","url":"https:\/\/uffizio.com\/wp-content\/uploads\/2022\/06\/traminlondon_0_o.jpeg","contentUrl":"https:\/\/uffizio.com\/wp-content\/uploads\/2022\/06\/traminlondon_0_o.jpeg","width":1280,"height":720,"caption":"traminlondon_0_o"},{"@type":"BreadcrumbList","@id":"https:\/\/uffizio.com\/es\/blog\/london-introduced-an-automatic-braking-system-in-the-tram\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/uffizio.com\/es\/"},{"@type":"ListItem","position":2,"name":"London introduced an automatic braking system in the tram"}]},{"@type":"WebSite","@id":"https:\/\/uffizio.com\/es\/#website","url":"https:\/\/uffizio.com\/es\/","name":"Oficina","description":"","publisher":{"@id":"https:\/\/uffizio.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/uffizio.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/uffizio.com\/es\/#organization","name":"Oficina","url":"https:\/\/uffizio.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/uffizio.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/uffizio.com\/wp-content\/uploads\/2025\/10\/Uffizio-logo.svg","contentUrl":"https:\/\/uffizio.com\/wp-content\/uploads\/2025\/10\/Uffizio-logo.svg","width":237,"height":35,"caption":"Uffizio"},"image":{"@id":"https:\/\/uffizio.com\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/uffizio.com\/es\/#\/schema\/person\/5475a82825addfcc6485fb7ddc195eba","name":"oficina","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/b77738c65df96915961877b1a9ce793a765d3357a4af4204e5d8c3416f362ce6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b77738c65df96915961877b1a9ce793a765d3357a4af4204e5d8c3416f362ce6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b77738c65df96915961877b1a9ce793a765d3357a4af4204e5d8c3416f362ce6?s=96&d=mm&r=g","caption":"uffizio"},"sameAs":["https:\/\/uffizio.com\/es\/"],"url":"https:\/\/uffizio.com\/es\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/uffizio.com\/es\/wp-json\/wp\/v2\/posts\/3728","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/uffizio.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/uffizio.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/uffizio.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/uffizio.com\/es\/wp-json\/wp\/v2\/comments?post=3728"}],"version-history":[{"count":0,"href":"https:\/\/uffizio.com\/es\/wp-json\/wp\/v2\/posts\/3728\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/uffizio.com\/es\/wp-json\/wp\/v2\/media\/3729"}],"wp:attachment":[{"href":"https:\/\/uffizio.com\/es\/wp-json\/wp\/v2\/media?parent=3728"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/uffizio.com\/es\/wp-json\/wp\/v2\/categories?post=3728"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/uffizio.com\/es\/wp-json\/wp\/v2\/tags?post=3728"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}