{"id":2391,"date":"2020-09-04T05:40:31","date_gmt":"2020-09-04T05:40:31","guid":{"rendered":"https:\/\/www.uffizio.com\/?p=2391"},"modified":"2026-05-20T04:11:34","modified_gmt":"2026-05-20T04:11:34","slug":"gps-enabled-e-rickshaws-will-see-a-big-leap-in-covid-19","status":"publish","type":"post","link":"https:\/\/uffizio.com\/es\/blog\/gps-enabled-e-rickshaws-will-see-a-big-leap-in-covid-19\/","title":{"rendered":"Los rickshaws el\u00e9ctricos con GPS experimentar\u00e1n un gran auge en el contexto de la COVID-19."},"content":{"rendered":"<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"538\" class=\"wp-image-9896\" src=\"https:\/\/www.uffizio.com\/wp-content\/uploads\/2020\/09\/gps-enablede-rickshaw-scaled-1-1024x538-1.jpg\" alt=\"gps-enabled-e-rickshaw\" srcset=\"https:\/\/uffizio.com\/wp-content\/uploads\/2020\/09\/gps-enablede-rickshaw-scaled-1-1024x538-1.jpg 1024w, https:\/\/uffizio.com\/wp-content\/uploads\/2020\/09\/gps-enablede-rickshaw-scaled-1-1024x538-1-300x158.jpg 300w, https:\/\/uffizio.com\/wp-content\/uploads\/2020\/09\/gps-enablede-rickshaw-scaled-1-1024x538-1-768x404.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">An Asian Road is incomplete without the hand-driven three-wheeled vehicles. From the petition to ban the use of human pulled carriage to its modification into a scooter with a cabin or Cycle fitted cabins, a Rickshaw is a blended form of tradition to the Asian Community. They are present in different models over the length and breadth of the world. Especially in India, Auto rickshaws are not simply vehicles they are decorated with the driver&#8217;s notion about life and love.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">El amarillo, el negro y el verde no son solo colores; se asocian a nuestra mente con una forma espec\u00edfica de autorickshaw. As\u00ed como la humanidad ha evolucionado, el rickshaw tambi\u00e9n lo ha hecho, con la reciente incorporaci\u00f3n de los rickshaws el\u00e9ctricos con GPS.<\/p>\r\n\r\n\r\n\r\n<h3>Impacto de la COVID-19\u00a0<\/h3>\r\n<p class=\"wp-block-paragraph\">El virus COVID-19, sin precedentes, impact\u00f3 toda la econom\u00eda. Un simple virus cambi\u00f3 por completo nuestro estilo de vida. Atr\u00e1s quedaron los d\u00edas en que salud\u00e1bamos a los autorickshaws, nos enfrent\u00e1bamos a constantes rechazos por parte de los conductores y regate\u00e1bamos para conseguir una tarifa m\u00e1s baja. Hoy en d\u00eda, somos extremadamente cautelosos al salir de casa, especialmente al usar el transporte p\u00fablico.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">La crisis de la COVID-19 ayud\u00f3 a la gente a innovar. El famoso dicho encaja perfectamente: \"La necesidad es la madre de la invenci\u00f3n\". En la reciente fase de desconfinamiento, el rickshaw el\u00e9ctrico es el medio de transporte preferido por muchos. Los rickshaws se desinfectan y, en su mayor\u00eda, est\u00e1n equipados con una pantalla separada del conductor. <a href=\"https:\/\/uffizio.com\/es\/blog\/personal-tracker-and-proximity-solution-for-safer-work-environment-during-covid-19\/\" target=\"_blank\" rel=\"noreferrer noopener\">mantener el distanciamiento social<\/a>Admiten pagos electr\u00f3nicos y cuentan con GPS.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">According to a study by Deloitte, 57% of Indians prefer to use ride-hailing services instead of using their vehicles. The population which is born after the 1980s even considers if they should buy a private vehicle or not. On-demand services like Uber and Ola for Taxi purpose is the trend for the country&#8217;s people to travel.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Una caracter\u00edstica que distingue el servicio a demanda de los rickshaws el\u00e9ctricos de la industria de Uber es su bajo costo y rentabilidad. La mayor parte de la poblaci\u00f3n de Asia pertenece a la clase media y media baja, que generalmente opta por los rickshaws en lugar de los taxis. Estos rickshaws ofrecen servicio puerta a puerta. El modelo actual de la aplicaci\u00f3n Jugnoo funciona con el mismo principio. En una presentaci\u00f3n, el cofundador de Jugnoo, Samar Singla, mencion\u00f3 que \"cada d\u00eda se realizan alrededor de 30 millones de viajes en auto en el pa\u00eds\".<\/p>\r\n\r\n\r\n\r\n<h3>C\u00f3mo elegir bicitaxis el\u00e9ctricos con GPS<\/h3>\r\n<p class=\"wp-block-paragraph\">Especialmente en estos tiempos, los autorickshaws con GPS que funcionan bajo demanda tienen un gran potencial. Los erickshaws pueden localizar la ubicaci\u00f3n exacta incluso si no se proporcionan datos precisos de la direcci\u00f3n.\u00a0<a href=\"https:\/\/uffizio.com\/es\/gps-tracker\/\" target=\"_blank\" rel=\"noreferrer noopener\">rastreador GPS<\/a>\u00a0El sistema localiza tu ubicaci\u00f3n exacta y el administrador del servicio elige al conductor m\u00e1s cercano para que te lleve hasta all\u00ed. Esto minimiza las confusiones al tener que guiar al conductor hasta tu ubicaci\u00f3n.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Es un medio de transporte viable para personas solas o familias peque\u00f1as, ya que garantiza un contacto m\u00ednimo durante el viaje. Incluso si viajas solo, el precio ser\u00e1 asequible.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Si te preocupa el medio ambiente, probablemente optar\u00e1s por los rickshaws el\u00e9ctricos. Estos generan una menor huella de carbono que un coche. Adem\u00e1s, su bajo peso y menor velocidad reducen el desgaste de las carreteras.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Si bien los rickshaws el\u00e9ctricos pueden ser la mejor opci\u00f3n para recorrer distancias medias y cortas, esto puede representar una importante fuente de ingresos para las familias que dependen de este veh\u00edculo de tres ruedas para su sustento.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">A pesar de <a href=\"https:\/\/uffizio.com\/es\/blog\/what-fleet-managers-can-do-to-safeguard-their-business-during-covid-19\/\">La COVID ha golpeado duramente a la industria de la movilidad.<\/a>\u00a0as a whole. There is a silver lining for E-rickshaws in the near future. According to &#8220;COVID-19 Impact on the E-Rickshaw Market Potential in India: Estimating Demand for E-Rickshaw and its Components by 2024-25&#8243;COVID 19 has created a dip in the curve of Demand and optimistically the demand for E-rickshaws will rise in the next 5-6 years.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">En resumen, la idea de los rickshaws el\u00e9ctricos con GPS beneficiar\u00eda a gran parte de la poblaci\u00f3n mundial. Esto representar\u00eda una fuente de ingresos para muchos y podr\u00eda satisfacer la demanda del resto de la poblaci\u00f3n que depende de un rickshaw para sus desplazamientos diarios.<\/p>","protected":false},"excerpt":{"rendered":"<p>An Asian Road is incomplete without the hand-driven three-wheeled vehicles. From the petition to ban the use of human pulled carriage to its modification into a scooter with a cabin or Cycle fitted cabins, a Rickshaw is a blended form of tradition to the Asian Community. They are present in different models over the length [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":9896,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[29],"tags":[31],"class_list":["post-2391","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","tag-gps-software"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>GPS Enabled E-Rickshaws will see a Big Leap In COVID-19<\/title>\n<meta name=\"description\" content=\"GPS enabled E-rickshaws is a big leap in the mobility industry. Helping the major population of the people around the globe.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/uffizio.com\/es\/blog\/gps-enabled-e-rickshaws-will-see-a-big-leap-in-covid-19\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"GPS Enabled E-Rickshaws will see a Big Leap In COVID-19\" \/>\n<meta property=\"og:description\" content=\"GPS enabled E-rickshaws is a big leap in the mobility industry. Helping the major population of the people around the globe.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/uffizio.com\/es\/blog\/gps-enabled-e-rickshaws-will-see-a-big-leap-in-covid-19\/\" \/>\n<meta property=\"og:site_name\" content=\"Uffizio\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-04T05:40:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-20T04:11:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/uffizio.com\/wp-content\/uploads\/2020\/09\/gps-enablede-rickshaw-scaled-1-1024x538-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"538\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"uffizio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"uffizio\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/uffizio.com\\\/es\\\/blog\\\/gps-enabled-e-rickshaws-will-see-a-big-leap-in-covid-19\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/uffizio.com\\\/es\\\/blog\\\/gps-enabled-e-rickshaws-will-see-a-big-leap-in-covid-19\\\/\"},\"author\":{\"name\":\"uffizio\",\"@id\":\"https:\\\/\\\/uffizio.com\\\/es\\\/#\\\/schema\\\/person\\\/5475a82825addfcc6485fb7ddc195eba\"},\"headline\":\"GPS Enabled E-Rickshaws will see a Big Leap In COVID-19\",\"datePublished\":\"2020-09-04T05:40:31+00:00\",\"dateModified\":\"2026-05-20T04:11:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/uffizio.com\\\/es\\\/blog\\\/gps-enabled-e-rickshaws-will-see-a-big-leap-in-covid-19\\\/\"},\"wordCount\":676,\"publisher\":{\"@id\":\"https:\\\/\\\/uffizio.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/uffizio.com\\\/es\\\/blog\\\/gps-enabled-e-rickshaws-will-see-a-big-leap-in-covid-19\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/uffizio.com\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/gps-enablede-rickshaw-scaled-1-1024x538-1.jpg\",\"keywords\":[\"GPS Software\"],\"articleSection\":[\"Blog\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/uffizio.com\\\/es\\\/blog\\\/gps-enabled-e-rickshaws-will-see-a-big-leap-in-covid-19\\\/\",\"url\":\"https:\\\/\\\/uffizio.com\\\/es\\\/blog\\\/gps-enabled-e-rickshaws-will-see-a-big-leap-in-covid-19\\\/\",\"name\":\"GPS Enabled E-Rickshaws will see a Big Leap In COVID-19\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/uffizio.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/uffizio.com\\\/es\\\/blog\\\/gps-enabled-e-rickshaws-will-see-a-big-leap-in-covid-19\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/uffizio.com\\\/es\\\/blog\\\/gps-enabled-e-rickshaws-will-see-a-big-leap-in-covid-19\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/uffizio.com\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/gps-enablede-rickshaw-scaled-1-1024x538-1.jpg\",\"datePublished\":\"2020-09-04T05:40:31+00:00\",\"dateModified\":\"2026-05-20T04:11:34+00:00\",\"description\":\"GPS enabled E-rickshaws is a big leap in the mobility industry. Helping the major population of the people around the globe.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/uffizio.com\\\/es\\\/blog\\\/gps-enabled-e-rickshaws-will-see-a-big-leap-in-covid-19\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/uffizio.com\\\/es\\\/blog\\\/gps-enabled-e-rickshaws-will-see-a-big-leap-in-covid-19\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/uffizio.com\\\/es\\\/blog\\\/gps-enabled-e-rickshaws-will-see-a-big-leap-in-covid-19\\\/#primaryimage\",\"url\":\"https:\\\/\\\/uffizio.com\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/gps-enablede-rickshaw-scaled-1-1024x538-1.jpg\",\"contentUrl\":\"https:\\\/\\\/uffizio.com\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/gps-enablede-rickshaw-scaled-1-1024x538-1.jpg\",\"width\":1024,\"height\":538,\"caption\":\"gps-enablede-rickshaw-scaled-1-1024x538-1\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/uffizio.com\\\/es\\\/blog\\\/gps-enabled-e-rickshaws-will-see-a-big-leap-in-covid-19\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/uffizio.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"GPS Enabled E-Rickshaws will see a Big Leap In COVID-19\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/uffizio.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/uffizio.com\\\/es\\\/\",\"name\":\"Uffizio\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/uffizio.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/uffizio.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/uffizio.com\\\/es\\\/#organization\",\"name\":\"Uffizio\",\"url\":\"https:\\\/\\\/uffizio.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/uffizio.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/uffizio.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Uffizio-logo.svg\",\"contentUrl\":\"https:\\\/\\\/uffizio.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Uffizio-logo.svg\",\"width\":237,\"height\":35,\"caption\":\"Uffizio\"},\"image\":{\"@id\":\"https:\\\/\\\/uffizio.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/uffizio.com\\\/es\\\/#\\\/schema\\\/person\\\/5475a82825addfcc6485fb7ddc195eba\",\"name\":\"uffizio\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b77738c65df96915961877b1a9ce793a765d3357a4af4204e5d8c3416f362ce6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b77738c65df96915961877b1a9ce793a765d3357a4af4204e5d8c3416f362ce6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b77738c65df96915961877b1a9ce793a765d3357a4af4204e5d8c3416f362ce6?s=96&d=mm&r=g\",\"caption\":\"uffizio\"},\"sameAs\":[\"https:\\\/\\\/uffizio.com\\\/es\\\/\"],\"url\":\"https:\\\/\\\/uffizio.com\\\/es\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Los rickshaws el\u00e9ctricos con GPS experimentar\u00e1n un gran auge en el contexto de la COVID-19.","description":"GPS enabled E-rickshaws is a big leap in the mobility industry. Helping the major population of the people around the globe.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/uffizio.com\/es\/blog\/gps-enabled-e-rickshaws-will-see-a-big-leap-in-covid-19\/","og_locale":"es_MX","og_type":"article","og_title":"GPS Enabled E-Rickshaws will see a Big Leap In COVID-19","og_description":"GPS enabled E-rickshaws is a big leap in the mobility industry. Helping the major population of the people around the globe.","og_url":"https:\/\/uffizio.com\/es\/blog\/gps-enabled-e-rickshaws-will-see-a-big-leap-in-covid-19\/","og_site_name":"Uffizio","article_published_time":"2020-09-04T05:40:31+00:00","article_modified_time":"2026-05-20T04:11:34+00:00","og_image":[{"width":1024,"height":538,"url":"https:\/\/uffizio.com\/wp-content\/uploads\/2020\/09\/gps-enablede-rickshaw-scaled-1-1024x538-1.jpg","type":"image\/jpeg"}],"author":"uffizio","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"uffizio","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/uffizio.com\/es\/blog\/gps-enabled-e-rickshaws-will-see-a-big-leap-in-covid-19\/#article","isPartOf":{"@id":"https:\/\/uffizio.com\/es\/blog\/gps-enabled-e-rickshaws-will-see-a-big-leap-in-covid-19\/"},"author":{"name":"uffizio","@id":"https:\/\/uffizio.com\/es\/#\/schema\/person\/5475a82825addfcc6485fb7ddc195eba"},"headline":"GPS Enabled E-Rickshaws will see a Big Leap In COVID-19","datePublished":"2020-09-04T05:40:31+00:00","dateModified":"2026-05-20T04:11:34+00:00","mainEntityOfPage":{"@id":"https:\/\/uffizio.com\/es\/blog\/gps-enabled-e-rickshaws-will-see-a-big-leap-in-covid-19\/"},"wordCount":676,"publisher":{"@id":"https:\/\/uffizio.com\/es\/#organization"},"image":{"@id":"https:\/\/uffizio.com\/es\/blog\/gps-enabled-e-rickshaws-will-see-a-big-leap-in-covid-19\/#primaryimage"},"thumbnailUrl":"https:\/\/uffizio.com\/wp-content\/uploads\/2020\/09\/gps-enablede-rickshaw-scaled-1-1024x538-1.jpg","keywords":["GPS Software"],"articleSection":["Blog"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/uffizio.com\/es\/blog\/gps-enabled-e-rickshaws-will-see-a-big-leap-in-covid-19\/","url":"https:\/\/uffizio.com\/es\/blog\/gps-enabled-e-rickshaws-will-see-a-big-leap-in-covid-19\/","name":"Los rickshaws el\u00e9ctricos con GPS experimentar\u00e1n un gran auge en el contexto de la COVID-19.","isPartOf":{"@id":"https:\/\/uffizio.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/uffizio.com\/es\/blog\/gps-enabled-e-rickshaws-will-see-a-big-leap-in-covid-19\/#primaryimage"},"image":{"@id":"https:\/\/uffizio.com\/es\/blog\/gps-enabled-e-rickshaws-will-see-a-big-leap-in-covid-19\/#primaryimage"},"thumbnailUrl":"https:\/\/uffizio.com\/wp-content\/uploads\/2020\/09\/gps-enablede-rickshaw-scaled-1-1024x538-1.jpg","datePublished":"2020-09-04T05:40:31+00:00","dateModified":"2026-05-20T04:11:34+00:00","description":"GPS enabled E-rickshaws is a big leap in the mobility industry. Helping the major population of the people around the globe.","breadcrumb":{"@id":"https:\/\/uffizio.com\/es\/blog\/gps-enabled-e-rickshaws-will-see-a-big-leap-in-covid-19\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/uffizio.com\/es\/blog\/gps-enabled-e-rickshaws-will-see-a-big-leap-in-covid-19\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/uffizio.com\/es\/blog\/gps-enabled-e-rickshaws-will-see-a-big-leap-in-covid-19\/#primaryimage","url":"https:\/\/uffizio.com\/wp-content\/uploads\/2020\/09\/gps-enablede-rickshaw-scaled-1-1024x538-1.jpg","contentUrl":"https:\/\/uffizio.com\/wp-content\/uploads\/2020\/09\/gps-enablede-rickshaw-scaled-1-1024x538-1.jpg","width":1024,"height":538,"caption":"gps-enablede-rickshaw-scaled-1-1024x538-1"},{"@type":"BreadcrumbList","@id":"https:\/\/uffizio.com\/es\/blog\/gps-enabled-e-rickshaws-will-see-a-big-leap-in-covid-19\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/uffizio.com\/es\/"},{"@type":"ListItem","position":2,"name":"GPS Enabled E-Rickshaws will see a Big Leap In COVID-19"}]},{"@type":"WebSite","@id":"https:\/\/uffizio.com\/es\/#website","url":"https:\/\/uffizio.com\/es\/","name":"Oficina","description":"","publisher":{"@id":"https:\/\/uffizio.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/uffizio.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/uffizio.com\/es\/#organization","name":"Oficina","url":"https:\/\/uffizio.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/uffizio.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/uffizio.com\/wp-content\/uploads\/2025\/10\/Uffizio-logo.svg","contentUrl":"https:\/\/uffizio.com\/wp-content\/uploads\/2025\/10\/Uffizio-logo.svg","width":237,"height":35,"caption":"Uffizio"},"image":{"@id":"https:\/\/uffizio.com\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/uffizio.com\/es\/#\/schema\/person\/5475a82825addfcc6485fb7ddc195eba","name":"oficina","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/b77738c65df96915961877b1a9ce793a765d3357a4af4204e5d8c3416f362ce6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b77738c65df96915961877b1a9ce793a765d3357a4af4204e5d8c3416f362ce6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b77738c65df96915961877b1a9ce793a765d3357a4af4204e5d8c3416f362ce6?s=96&d=mm&r=g","caption":"uffizio"},"sameAs":["https:\/\/uffizio.com\/es\/"],"url":"https:\/\/uffizio.com\/es\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/uffizio.com\/es\/wp-json\/wp\/v2\/posts\/2391","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/uffizio.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/uffizio.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/uffizio.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/uffizio.com\/es\/wp-json\/wp\/v2\/comments?post=2391"}],"version-history":[{"count":0,"href":"https:\/\/uffizio.com\/es\/wp-json\/wp\/v2\/posts\/2391\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/uffizio.com\/es\/wp-json\/wp\/v2\/media\/9896"}],"wp:attachment":[{"href":"https:\/\/uffizio.com\/es\/wp-json\/wp\/v2\/media?parent=2391"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/uffizio.com\/es\/wp-json\/wp\/v2\/categories?post=2391"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/uffizio.com\/es\/wp-json\/wp\/v2\/tags?post=2391"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}